{"id":9928,"date":"2025-11-19T17:00:00","date_gmt":"2025-11-19T16:00:00","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=9928"},"modified":"2025-11-14T23:37:26","modified_gmt":"2025-11-14T22:37:26","slug":"les-tuniques-bleues-69-lincoln-dans-la-ligne-de-mire","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2025\/11\/19\/les-tuniques-bleues-69-lincoln-dans-la-ligne-de-mire\/","title":{"rendered":"Les Tuniques Bleues 69 &#8211; Lincoln dans la ligne de mire"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-46c2b400ce34e263a7ce9d1d1a98b7ad wp-block-paragraph\"><strong>Peine de mort pour Blutch<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/5YU7DccicsEcqDnD2IdXhK?si=uHf60fBxT0KEr2gJzgXXFw\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/zF4RqTdnLwY\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-J\u2019ai tout vu ! Bien jou\u00e9, Sergent ! Ce l\u00e2che individu est la honte du 22<sup>\u00e8me <\/sup>de cavalerie ! Il sera traduit en cour martiale !<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Bah\u2026 Est-ce vraiment n\u00e9cessaire, mon Capitaine ? Juste un moment d\u2019\u00e9garement\u2026<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Qui lui vaudra le peloton d\u2019ex\u00e9cution ! D\u00e9sol\u00e9, mais le r\u00e8glement, c\u2019est le r\u00e8glement !\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pour une fois que Stilman s\u2019aventure sur un champ de bataille, le Caporal Blutch n\u2019a pas de chance. Le haut grad\u00e9 a vu le Sergent Chesterfield rappeler son subordonn\u00e9 \u00e0 l\u2019ordre alors qu\u2019il tentait une \u00e9ni\u00e8me fois de plus de d\u00e9serter. Cela va lui valoir la punition supr\u00eame : la cour martiale. Attendu son insubordination, Blutch est condamn\u00e9 \u00e0 la peine capitale. La sentence sera ex\u00e9cut\u00e9e le lendemain \u00e0 l\u2019aube. Son sup\u00e9rieur va tout faire pour le sortir de ce mauvais pas, mais ce n\u2019est pas de lui que viendra son salut. Dans la cellule \u00e0 c\u00f4t\u00e9 de la sienne, se trouve Isabella Boyd, condamn\u00e9e \u00e0 mort pour intelligence avec l\u2019ennemi. Avec sa complicit\u00e9, ils vont parvenir \u00e0 s\u2019\u00e9vader dans la nuit.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"908\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-1.jpg\" alt=\"\" class=\"wp-image-9929\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-1.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-1-225x300.jpg 225w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Lambil, Neidhardt, Leonardo &#8211; Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Isabella Boyd a une dent contre les yankees depuis qu\u2019ils ont br\u00fbl\u00e9 et saccag\u00e9 sa plantation familiale en G\u00e9orgie. Elle a jur\u00e9 sur les ruines de son foyer de consacrer le reste de son existence \u00e0 se venger des nordistes. Elle a ralli\u00e9 un r\u00e9seau secret pilot\u00e9 par la conf\u00e9d\u00e9ration et qui organise des attentats cibl\u00e9s. Elle propose \u00e0 Blutch de les rejoindre. A Baltimore, ses complices proposent de tester la loyaut\u00e9 de Blutch en lui confiant une mission : \u00e9liminer une cible nordiste qu\u2019ils allaient lui d\u00e9signer. Belle s\u2019en porte garante. Depuis la chambre 212 du Rail Road Hotel, il va falloir abattre le g\u00e9n\u00e9ral Scott, responsable yankee d\u2019un blocus qui affame les conf\u00e9d\u00e9r\u00e9s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"896\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-2.jpg\" alt=\"\" class=\"wp-image-9930\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-2.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-2-228x300.jpg 228w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Lambil, Neidhardt, Leonardo &#8211; Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Deuxi\u00e8me sc\u00e9nario de Fred Neidhardt et deuxi\u00e8me coup de ma\u00eetre. En mettant Blutch dans une situation inextricable, il repousse les limites atteintes par Raoul Cauvin dans le m\u00eame genre de situation. Ce n\u2019est pas que l\u2019\u00e9l\u00e8ve d\u00e9passe le ma\u00eetre, mais il se sert des exp\u00e9riences de son mentor comme rampe de lancement pour pousser le curseur plus loin. Isabella Boyd, dite Belle, a vraiment exist\u00e9. C\u2019est incroyable de trouver des anecdotes v\u00e9ridiques de la guerre de S\u00e9cession apr\u00e8s 69 albums. Alors que Cauvin critiquait la guerre, Neidhardt raille la peine de mort. Au dessin, on pardonne au v\u00e9t\u00e9ran Willy Lambil les quelques fautes de proportions. Le t\u00f4lier reste ma\u00eetre de sa s\u00e9rie. Il fait partie de ces auteurs comme Roger Leloup qui ne quiteront jamais leur table \u00e0 dessin. Ce sont les Michel Drucker du Neuvi\u00e8me Art.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"907\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-3.jpg\" alt=\"\" class=\"wp-image-9931\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-3.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69-3-225x300.jpg 225w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Lambil, Neidhardt, Leonardo &#8211; Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Soixante-neuvi\u00e8me chevauch\u00e9e et les bleus sont toujours aussi frais. Quand un classique a encore une telle force apr\u00e8s tant d\u2019ann\u00e9es, c\u2019est qu\u2019il y a quelque chose de magique.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie&nbsp;:<\/strong> Les Tuniques Bleues<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome : <\/strong>69 &#8211; Lincoln dans la ligne de mire<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;: <\/strong>Aventure\/Histoire\/Humour<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario&nbsp;: <\/strong>Fred Neidhardt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins&nbsp;: <\/strong>WillyLambil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Couleurs&nbsp;: <\/strong>Leonardo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Dupuis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 9782808507660<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 12,50 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Peine de mort pour Blutch \u00ab\u00a0-J\u2019ai tout vu ! Bien jou\u00e9, Sergent ! Ce l\u00e2che individu est la honte du 22\u00e8me de cavalerie ! Il sera traduit en cour martiale ! -Bah\u2026 Est-ce vraiment n\u00e9cessaire, mon Capitaine ? Juste un moment d\u2019\u00e9garement\u2026 -Qui lui vaudra le peloton d\u2019ex\u00e9cution ! D\u00e9sol\u00e9, mais le r\u00e8glement, c\u2019est le &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2025\/11\/19\/les-tuniques-bleues-69-lincoln-dans-la-ligne-de-mire\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Les Tuniques Bleues 69 &#8211; Lincoln dans la ligne de mire\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":9932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,93,105,25,19],"tags":[7,32],"class_list":["post-9928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-classique-chroniques","category-franco-belge","category-histoire","category-humour","tag-editions-dupuis","tag-journal-spirou"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/11\/Les-tuniques-bleues-69.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=9928"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9928\/revisions"}],"predecessor-version":[{"id":9933,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9928\/revisions\/9933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/9932"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=9928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=9928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=9928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}