{"id":9313,"date":"2025-10-11T12:00:00","date_gmt":"2025-10-11T10:00:00","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=9313"},"modified":"2025-09-30T22:41:15","modified_gmt":"2025-09-30T20:41:15","slug":"boulevard-tintin-tintin-cest-laventure-25-qui-sont-les-tintin-daujourdhui","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2025\/10\/11\/boulevard-tintin-tintin-cest-laventure-25-qui-sont-les-tintin-daujourdhui\/","title":{"rendered":"Boulevard Tintin \u2013 Tintin c\u2019est l\u2019aventure 25 \u2013 Qui sont les Tintin d\u2019aujourd\u2019hui\u00a0?"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Chaque aventurier est un peu Tintin<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/4VBN81X53S0tVOipLxOAKk?si=y2GwHp8ESTCC01LWwzhLTg\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/ukHtAIS13co\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Et toi, l\u2019aventure ne te manque pas&nbsp;? Assis toute la journ\u00e9e&nbsp;?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Haha&nbsp;! Mais pas du tout&nbsp;! Regarde-\u00e7a&nbsp;! L\u2019aventure est l\u00e0, sous mon crayon ! L\u2019aventure ne termine jamais. Tant qu\u2019il y aura du monde et des BD pour y r\u00eaver.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans une mise en abime de quatre planches, l\u2019autrice Alix Garin s\u2019immerge dans les coulisses de la cr\u00e9ation. Exp\u00e9rience, inspiration et expression sont les trois piliers du cr\u00e9ateur. La statue de Herg\u00e9 va lui apprendre que raconter une histoire, c\u2019est avant tout partager un regard, c\u2019est partir \u00e0 l\u2019aventure pour un voyage qui n\u2019aura pas de fin tant qu\u2019il y aura des gens pour ce partage et ce r\u00eave. On ne pouvait pas r\u00eaver plus bel argument pour le dernier num\u00e9ro du magazine co-\u00e9dit\u00e9 par Moulinsart et G\u00e9o&nbsp;: Tintin, c\u2019est l\u2019aventure.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"968\" height=\"680\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP2-1-1.jpg\" alt=\"\" class=\"wp-image-9319\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP2-1-1.jpg 968w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP2-1-1-300x211.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP2-1-1-768x540.jpg 768w\" sizes=\"auto, (max-width: 968px) 100vw, 968px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9\/Tintinimaginatio 2025<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Comme d\u2019habitude, tous les articles sont illustr\u00e9s par des images de Tintin et les sujets replac\u00e9s au c\u0153ur de ses aventures. Dans la rubrique Panorama, on se demande entre autres si des animaux d\u2019esp\u00e8ces diff\u00e9rentes peuvent communiquer. C\u2019est l\u2019occasion de revenir sur l\u2019inimiti\u00e9 entre Milou et la pie voleuse des Bijoux de la Castafiore. Dans un sublime portfolio, on (re)d\u00e9couvre un Herg\u00e9 au crayon vagabond, \u00e0 travers les archives personnelles de l\u2019auteur&nbsp;: images de Tintin \u00e9videmment, mais aussi illustrations pour des livres, croquis de recherche\u2026 et papier peint&nbsp;! L\u2019essentiel du recueil est consacr\u00e9 aux Tintin d\u2019aujourd\u2019hui, ces aventuriers, nourris ou pas par les aventures du reporter, mais marchant tous sur ses pas\u2026 pour de vrai.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"968\" height=\"680\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP4-1-1.jpg\" alt=\"\" class=\"wp-image-9320\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP4-1-1.jpg 968w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP4-1-1-300x211.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP4-1-1-768x540.jpg 768w\" sizes=\"auto, (max-width: 968px) 100vw, 968px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9\/Tintinimaginatio 2025<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Leurs profils sont tr\u00e8s divers. On trouve la premi\u00e8re journaliste sous-marini\u00e8re Nathalie Guibert, un m\u00e9decin en terre inconnue Ana\u00efs P\u00e9lier, un explorateur des climats extr\u00eames Christian Clot, une des plus c\u00e9l\u00e8bres navigatrices Isabelle Autissier, et bien d\u2019autres encore. Il y a aussi des \u00e9crivains comme Alexis Jenni, surnomm\u00e9 l\u2019anti-voyageur, qui a un rapport litt\u00e9raire \u00e0 l\u2019id\u00e9e d\u2019aventure, ou encore Sonja Delzongle qui est partie en Ecosse, terre de l\u00e9gendes, \u00e0 la demande de son \u00e9diteur, sur les traces du monstre du Loch Ness. Le titre de son livre ne fait pas de doute quant au clin d\u2019\u0153il \u00e0 Herg\u00e9&nbsp;: Sur l\u2019\u00eele noire.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"968\" height=\"680\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP5-1-1.jpg\" alt=\"\" class=\"wp-image-9321\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP5-1-1.jpg 968w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP5-1-1-300x211.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/DP5-1-1-768x540.jpg 768w\" sizes=\"auto, (max-width: 968px) 100vw, 968px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9\/Tintinimaginatio 2025<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le recueil se cl\u00f4t par l\u2019extrait de l\u2019album Antipodes, sign\u00e9 David B. et Eric Lamb\u00e9, paru chez Casterman, racontant l\u2019aventure d\u2019un colon fran\u00e7ais dans une tribu d\u2019anthropophages au Br\u00e9sil au XVI<sup>\u00e8me<\/sup> si\u00e8cle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec ce vingt-cinqui\u00e8me num\u00e9ro, le mook Tintin c\u2019est l\u2019aventure tire sa r\u00e9v\u00e9rence. L\u2019aventure \u00e9ditoriale aura \u00e9t\u00e9 une merveilleuse invitation au voyage. Celui-ci est loin d\u2019\u00eatre termin\u00e9, parce que quand on a fini de lire Tintin, on peut recommencer \u00e0 lire Tintin. On y trouvera toujours quelque chose de nouveau.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>Tintin c\u2019est l\u2019aventure<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;: <\/strong>25 \u2013 Qui sont les Tintin d\u2019aujourd\u2019hui&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;: <\/strong>Reportage<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9dactrice en chef&nbsp;: <\/strong>Myrtille Delamarche<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Directeur \u00e9ditorial :<\/strong> Didier Platteau<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario&nbsp;&amp; Dessins&nbsp;: <\/strong>Herg\u00e9<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Moulinsart\/G\u00e9o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>144<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 19,99 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Chaque aventurier est un peu Tintin \u00ab\u00a0-Et toi, l\u2019aventure ne te manque pas&nbsp;? Assis toute la journ\u00e9e&nbsp;? -Haha&nbsp;! Mais pas du tout&nbsp;! Regarde-\u00e7a&nbsp;! L\u2019aventure est l\u00e0, sous mon crayon ! L\u2019aventure ne termine jamais. Tant qu\u2019il y aura du monde et des BD pour y r\u00eaver.\u00a0\u00bb Dans une mise en abime de quatre planches, l\u2019autrice &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2025\/10\/11\/boulevard-tintin-tintin-cest-laventure-25-qui-sont-les-tintin-daujourdhui\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Boulevard Tintin \u2013 Tintin c\u2019est l\u2019aventure 25 \u2013 Qui sont les Tintin d\u2019aujourd\u2019hui\u00a0?\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":9322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[73,16,74,113,878],"tags":[1014],"class_list":["post-9313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-chroniques","category-evenement","category-ouvrage-detude","category-tintin","tag-editions-moulinsart"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/09\/TINTIN-25_COUV__compressed.jpg","_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=9313"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9313\/revisions"}],"predecessor-version":[{"id":9323,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/9313\/revisions\/9323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/9322"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=9313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=9313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=9313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}