{"id":8046,"date":"2025-04-18T00:27:30","date_gmt":"2025-04-17T22:27:30","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=8046"},"modified":"2025-04-18T00:27:30","modified_gmt":"2025-04-17T22:27:30","slug":"adelin-irina-4-la-cite-ardente","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2025\/04\/18\/adelin-irina-4-la-cite-ardente\/","title":{"rendered":"Adelin &#038; Irina 4 \u2013 La cit\u00e9 ardente"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-b6f95e980ec0ef30d38563630845d0b3 wp-block-paragraph\"><strong>Fantaisy Fantasy<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/creators.spotify.com\/pod\/show\/laurent-lafourcade\/episodes\/Adelin &amp; Irina 4-e31hm73\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/WZZuooQoG7o\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Hein ? Qu&rsquo;est-ce que\u2026 Qui \u00eates-vous ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Princesse Irina, je pr\u00e9sume ? Permettez-moi de me pr\u00e9senter : mon nom est Derr-Leth. Je suis l&rsquo;\u00e9x\u00e9cuteur testamantaire du sorcier Magul. Je suis venu vous demander de l&rsquo;aide pour une mission tr\u00e8s importante\u2026 Si vous pouviez m&rsquo;accorder quelques minutes\u2026\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9p\u00e9e de la domination conf\u00e8re \u00e0 son d\u00e9tenteur le pouvoir d&rsquo;imposer son autorit\u00e9 \u00e0 tous ceux qui sont mis en sa pr\u00e9sence. Forg\u00e9e par le sorcier Magul \u00e0 la suite d&rsquo;un pacte d\u00e9moniaque, elle fut cach\u00e9e au centre d&rsquo;une \u00eele labyrinthe truff\u00e9e de pi\u00e8ges et de monstres. Objet de toutes les convoitises, nombreux sont ceux qui ont tent\u00e9 de mettre la main dessus : Dona Miranda, Cirro le d\u00e9moniste, Zark, ainsi que la princesse Irina. Une seule personne a r\u00e9cup\u00e9r\u00e9 ce super top gadget trop cool, c&rsquo;est Belinda, l&rsquo;assistante de Cirro, celle qui vient du futur. Elle a niqu\u00e9 tous les monstres et lout\u00e9 tous les pi\u00e8ges. C&rsquo;est hypra-g\u00e9nial. Elle va pouvoir commander \u00e0 tout le monde. Voici donc que Belinda quitte l&rsquo;\u00eele. Il ne lui faudra pas longtemps pour devenir une dictatrice comme il se doit.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"973\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-2.jpg\" alt=\"\" class=\"wp-image-8047\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-2.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-2-210x300.jpg 210w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Nico Van de Walle \u2013 Editions du Tiroir<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Alors qu&rsquo;elle \u00e9tait en train de dicter pour m\u00e9moire ses exploits \u00e0 son page Adelin, la princesse Irina re\u00e7oit la visite de Derr-Leth, l&rsquo;ex\u00e9cuteur testamentaire du sorcier Magul. Il est venu lui demander de l&rsquo;aide pour une mission de la plus haute importance : affronter cette Belinda \u00e0 l&rsquo;autre bout du monde, dans un pays qu&rsquo;elle a conquis, o\u00f9 elle a tout pouvoir et dont tous les sujets l&rsquo;adorent. Comme Irina a tenu dans ses mains \u00e0 moment donn\u00e9 l&rsquo;\u00e9p\u00e9e de la domination, elle est immunis\u00e9e contre son pouvoir. Belinda compte \u00e9tendre sa domination sur les royaumes avoisinants. Derr-Leth recrute donc une arm\u00e9e de mercenaires, tous immunis\u00e9s pour diverses raisons, afin de subtiliser l&rsquo;\u00e9p\u00e9e et la lui ramener pour la remettre \u00e0 sa place.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"982\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-3.jpg\" alt=\"\" class=\"wp-image-8048\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-3.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-3-208x300.jpg 208w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Nico Van de Walle \u2013 Editions du Tiroir<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Adelin et Irina est une s\u00e9rie d&rsquo;Hero\u00efc-Fantasy \u00e0 prendre au second degr\u00e9. Avec un ton parodique et un humour parfois trash, elle est plus proche de Lanfeust de Troy que des Mondes d&rsquo;Aquilon. Nico VanDeWalle est un sale gosse. \u00c7a se voit, \u00e7a se lit. Ses personnages sont aussi malins que cr\u00e9tins. Le sc\u00e9nariste se permet tout. Ce n&rsquo;est parce qu&rsquo;on a eu la t\u00eate coup\u00e9e dans un \u00e9pisode pr\u00e9c\u00e9dent qu&rsquo;on ne peut pas revenir. Les femmes sont \u00e0 la fois sexys et f\u00e9ministes. Le m\u00e2le alpha n&rsquo;a pas le grand r\u00f4le. Le dessinateur rel\u00e8ve le d\u00e9fi de sc\u00e8nes de foules et de combats. On en prend plein les yeux. Nico VanDeWalle prouve que le genre, quand il sait se renouveler, a encore de beaux jours devant lui.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"970\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-4.jpg\" alt=\"\" class=\"wp-image-8049\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-4.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-4-210x300.jpg 210w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Nico Van de Walle \u2013 Editions du Tiroir<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Adelin et Irina\u00a0\u00bb r\u00e9g\u00e9n\u00e8re le style de \u00ab\u00a0Donjons et dragons\u00a0\u00bb tout en respectant son ADN. Entre cette s\u00e9rie et Rubine 90&rsquo;s, Nico VanDeWalle devient l&rsquo;un des piliers incontournables des Editions du Tiroir.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>Adelin &amp; Irina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;:<\/strong> 4 \u2013 La cit\u00e9 ardente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre\u00a0: <\/strong>Hero\u00efc Fantasy<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario, Dessins\u00a0&amp; Couleurs\u00a0: <\/strong>Nico Van de Walle<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Editions du Tiroir<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Collection&nbsp;:<\/strong> L\u2019aventure<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">ISBN&nbsp;: 9782931251164<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : 48<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 16 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Fantaisy Fantasy \u00ab\u00a0-Hein ? Qu&rsquo;est-ce que\u2026 Qui \u00eates-vous ? -Princesse Irina, je pr\u00e9sume ? Permettez-moi de me pr\u00e9senter : mon nom est Derr-Leth. Je suis l&rsquo;\u00e9x\u00e9cuteur testamantaire du sorcier Magul. Je suis venu vous demander de l&rsquo;aide pour une mission tr\u00e8s importante\u2026 Si vous pouviez m&rsquo;accorder quelques minutes\u2026\u00a0\u00bb L&rsquo;\u00e9p\u00e9e de la domination conf\u00e8re \u00e0 son &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2025\/04\/18\/adelin-irina-4-la-cite-ardente\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Adelin &#038; Irina 4 \u2013 La cit\u00e9 ardente\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":8050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,329],"tags":[106],"class_list":["post-8046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-heroic-fantasy","tag-editions-du-tiroir"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/04\/Adelin-et-Irina-4-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/8046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=8046"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/8046\/revisions"}],"predecessor-version":[{"id":8051,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/8046\/revisions\/8051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/8050"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=8046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=8046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=8046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}