{"id":7143,"date":"2025-01-15T15:29:59","date_gmt":"2025-01-15T14:29:59","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=7143"},"modified":"2025-01-15T17:10:09","modified_gmt":"2025-01-15T16:10:09","slug":"boulevard-bd-dor-2024","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2025\/01\/15\/boulevard-bd-dor-2024\/","title":{"rendered":"Boulevard BD d&rsquo;Or 2024"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Bobigny 1972<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le prix Boulevard BD d&rsquo;Or du meilleur album est attribu\u00e9 cette ann\u00e9e pour la deuxi\u00e8re fois. Le troph\u00e9e revient \u00e0 <strong>Bobigny 1972<\/strong>, sc\u00e9naris\u00e9 par Marie Bardiaux-Va\u00efente et dessin\u00e9 par Carole Maurel, paru aux \u00e9ditions Gl\u00e9nat. Il succ\u00e8de \u00e0 Les vies de Charlie, de Kid Toussaint et Aur\u00e9lie Guarino.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Bobigny-1972-couv-1-766x1024.jpg\" alt=\"\" class=\"wp-image-6621\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Bobigny-1972-couv-1-766x1024.jpg 766w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Bobigny-1972-couv-1-224x300.jpg 224w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Bobigny-1972-couv-1-768x1026.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Bobigny-1972-couv-1.jpg 835w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab\u00a0-Laisse-moi entrer, Marie-Claire\u2026 Que je te voie. Savoir si je dois t&rsquo;amener chez le Docteur. Ch\u00e9rie, que se passe-t-il ? Pourquoi tu pleures ? Ce n&rsquo;est pas grave, voyons\u2026 Des coliques\u2026 Marie-Claire\u2026. Marie-Claire. Tu dois me raconter ce qui s&rsquo;est pass\u00e9. Et tu dois me dire quand cela est arriv\u00e9.\u00a0\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1971. Marie-Claire a 15 ans. Elle n&rsquo;a pas fait l&rsquo;amour. Il l&rsquo;a forc\u00e9e. Il l&rsquo;a forc\u00e9e. Elle est enceinte. Il l&rsquo;a forc\u00e9e&#8230; Il l&rsquo;a forc\u00e9e\u2026 Marie-Claire ne veut pas de cet enfant. Sa m\u00e8re l&rsquo;accompagne dans sa d\u00e9marche. Comme des milliers de femmes, elle va aller voir une faiseuse d&rsquo;anges\u2026 pour avorter. D\u00e9but 1972, sur d\u00e9nonciation du violeur, Marie-Claire et Mich\u00e8le, sa m\u00e8re, sont arr\u00eat\u00e9es et interrog\u00e9es par la police. \u00ab\u00a0Quiconque par aliments, breuvages, m\u00e9dicaments, man\u0153uvres, violences ou par tout autre moyen aura procur\u00e9 ou tent\u00e9 de procurer l&rsquo;avortement d&rsquo;une femme enceinte ou suppos\u00e9e enceinte, qu&rsquo;elle y ait consenti ou non, sera puni d&rsquo;un emprisonnement d&rsquo;un an \u00e0 cinq ans, et d&rsquo;une amende de 1800 F \u00e0 100 000 F\u2026\u00a0\u00bb Les deux femmes sont lib\u00e9r\u00e9es en attendant le proc\u00e8s. Quelques mois plus t\u00f4t, 343 femmes ont lanc\u00e9 un appel r\u00e9clamant l&rsquo;avortement libre. Parmi elles, la c\u00e9l\u00e8bre avocate Gis\u00e8le Halimi. Mich\u00e8le Chevalier d\u00e9cide d&rsquo;aller la rencontrer pour qu&rsquo;elle d\u00e9fende sa fille, mais elle n&rsquo;a pas d&rsquo;argent pour la payer. Pour Halimi, il n&rsquo;y a pas de probl\u00e8me d&rsquo;argent. Il n&rsquo;y aura pas de frais si la famille la laisse agir. L&rsquo;affaire sera m\u00e9diatis\u00e9e afin de pousser l&rsquo;\u00e9tat \u00e0 changer la loi. La soci\u00e9t\u00e9 patriarcale est-elle pr\u00eate \u00e0 faire \u00e9voluer sa mentalit\u00e9 ?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-744x1024.jpg\" alt=\"\" class=\"wp-image-4256\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-744x1024.jpg 744w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-218x300.jpg 218w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-768x1058.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-1116x1536.jpg 1116w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-1487x2048.jpg 1487w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-2-scaled.jpg 1859w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Maurel, Bardiaux-Va\u00efente &#8211; Gl\u00e9nat<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Avec Bobigny 1972, c&rsquo;est tout le parcours du combattant pour l&rsquo;IVG qui est racont\u00e9 \u00e0 travers une histoire bas\u00e9e sur des faits r\u00e9els, le proc\u00e8s de Marie-Claire Chevalier. La loi Veil est en ligne de mire, mais avant d&rsquo;en arriver l\u00e0, il aura fallu tout le talent et la puissance d&rsquo;une Gis\u00e8le Halimi, avocate qui r\u00e9ussit \u00e0 embarquer l&rsquo;opinion publique. Carole Maurel met en sc\u00e8ne cet \u00e9v\u00e9nement avec une pudeur incroyable. Son graphisme r\u00e9unit les genres et transpire d&rsquo;\u00e9motion. Pour rester dans la militance : Carole Maurel, futur Grand Prix d&rsquo;Angoul\u00eame ! Marie Bardiaux-Va\u00efente montre \u00e0 toutes les femmes du XXI<sup>\u00e8me<\/sup> si\u00e8cle qui l&rsquo;ignoraient qu&rsquo;il aura fallu se battre il y a cinquante ans pour qu&rsquo;elles connaissent enfin la justice de leur libert\u00e9. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"746\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-746x1024.jpg\" alt=\"\" class=\"wp-image-4257\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-746x1024.jpg 746w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-219x300.jpg 219w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-768x1054.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-1119x1536.jpg 1119w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-1492x2048.jpg 1492w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/02\/Bobigny-3-scaled.jpg 1865w\" sizes=\"auto, (max-width: 746px) 100vw, 746px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Maurel, Bardiaux-Va\u00efente &#8211; Gl\u00e9nat<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Bobigny 1972 raconte un pan de la politique de la V<sup>\u00e8me<\/sup> R\u00e9publique. L&rsquo;album explique comment les mentalit\u00e9s ont \u00e9volu\u00e9 dans le sens de la fraternit\u00e9 (et de la sororit\u00e9), de la libert\u00e9 et surtout surtout de l&rsquo;\u00e9galit\u00e9. Au-del\u00e0 de \u00e7a, en 2024, les femmes prennent enfin le pouvoir dans le milieu de la bande dessin\u00e9e et c&rsquo;est tant mieux.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"703\" height=\"563\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/Boulevard-BD-dor-2024-1.jpg\" alt=\"\" class=\"wp-image-7146\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/Boulevard-BD-dor-2024-1.jpg 703w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/Boulevard-BD-dor-2024-1-300x240.jpg 300w\" sizes=\"auto, (max-width: 703px) 100vw, 703px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>One shot : <\/strong>Bobigny 1972<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;: <\/strong>Histoire<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario : <\/strong>Marie Bardiaux-Va\u00efente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins &amp; Couleurs&nbsp;: <\/strong>Carole Maurel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Gl\u00e9nat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;: <\/strong>978234405<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>164<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 22 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Bobigny 1972 Le prix Boulevard BD d&rsquo;Or du meilleur album est attribu\u00e9 cette ann\u00e9e pour la deuxi\u00e8re fois. Le troph\u00e9e revient \u00e0 Bobigny 1972, sc\u00e9naris\u00e9 par Marie Bardiaux-Va\u00efente et dessin\u00e9 par Carole Maurel, paru aux \u00e9ditions Gl\u00e9nat. Il succ\u00e8de \u00e0 Les vies de Charlie, de Kid Toussaint et Aur\u00e9lie Guarino. \u00ab\u00a0-Laisse-moi entrer, Marie-Claire\u2026 Que je &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2025\/01\/15\/boulevard-bd-dor-2024\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Boulevard BD d&rsquo;Or 2024\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":7145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[73,74],"tags":[59],"class_list":["post-7143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-evenement","tag-editions-glenat"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/Boulevard-BD-dor-2024.jpg","_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/7143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=7143"}],"version-history":[{"count":8,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/7143\/revisions"}],"predecessor-version":[{"id":7156,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/7143\/revisions\/7156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/7145"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=7143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=7143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=7143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}