{"id":6993,"date":"2025-01-06T21:45:20","date_gmt":"2025-01-06T20:45:20","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=6993"},"modified":"2025-01-06T21:45:20","modified_gmt":"2025-01-06T20:45:20","slug":"west-fantasy-3-lorc-le-juge-et-le-marshal-4-lorc-le-banquier-et-lassassin","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2025\/01\/06\/west-fantasy-3-lorc-le-juge-et-le-marshal-4-lorc-le-banquier-et-lassassin\/","title":{"rendered":"West Fantasy 3 \u2013 L&rsquo;orc, le juge et le marshal \/ 4 \u2013 L&rsquo;orc, le banquier et l&rsquo;assassin"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-192c8c01492baca2217effad5d2e82c8 wp-block-paragraph\"><strong>La loi du plus colt<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/creators.spotify.com\/pod\/show\/laurent-lafourcade\/episodes\/West-Fantasy-3--4-e2t1ht6\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/bZDcZf1okOE\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong><em>\u00ab\u00a0-Et le complice que vous m&rsquo;aviez promis pour m&rsquo;aider, o\u00f9 est-il ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Justement ! M., voici Yaretsi.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Elle empeste l&rsquo;alcool et le tabac.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-J&rsquo;\u00e9tais prise dans une partie de poker que je pouvais pas abandonner, et au poker, on boit et on fume, ma jolie ! On se contente pas d&rsquo;amour et d&rsquo;eau b\u00e9nite.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une bande de pistoleros attaque un train de voyageur en plein Ouest sauvage. Alors qu&rsquo;elle croyait diriger son groupe, l&rsquo;elfe Yaretsi se fait trahir par les membres de sa troupe qui veulent l&rsquo;\u00e9liminer. Elle ne doit son salut qu&rsquo;au Marshal Douglas Reeves qui la tire de ce bien mauvais pas. Pendant ce temps, \u00e0 Los Pazes, un \u00e9trange juge muet et sa s\u0153ur font la loi. Robert Abraham Anderson est surnomm\u00e9 le juge silence. Il forme avec Rachel un duo indissociable depuis que tout petit on lui eut coup\u00e9 la langue dans des conditions sordides. Quand Yaretsi va d\u00e9barquer dans la ville, tout ce petit monde va se d\u00e9couvrir un objectif de vengeance commun. Va y avoir du r\u00e8glement de comptes dans l&rsquo;air et, sans goudron, certains vont y laisser des plumes. C&rsquo;est l&rsquo;histoire de l&rsquo;orc, du juge et du marshal.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"981\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-1-1.jpg\" alt=\"\" class=\"wp-image-6995\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-1-1.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-1-1-208x300.jpg 208w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Corduri\u00e9, Bordier, Nanjan \u2013 Oxymore<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Tout comme le marshal Reeves \u00e9tait le fil conducteur entre les tomes 2 et 3, les histoires \u00e9tant cependant ind\u00e9pendantes, l&rsquo;orc Yaretsi va nous accompagner dans le volume suivant, avec un banquier et un assassin. S\u0153ur M., une nonne tortur\u00e9e, s&rsquo;\u00e9vade apr\u00e8s avoir trucid\u00e9 ses bourreaux. De son c\u00f4t\u00e9, Anson H. Renfield, dit le banquier, tente de faire main basse sur la nation. En pleine expansion vers l&rsquo;Ouest, le pays pourrait devenir le plus riche et le plus puissant du monde. Admirateur de la magie des peuples natifs, il tente de les convaincre de s&rsquo;allier pour tirer le meilleur de leurs deux mondes\u2026 mais \u00e9videmment \u00e0 son grand profit \u00e0 lui. Appartenant \u00e0 l&rsquo;ordre de Saint-Catherine, S\u0153ur M. a pour mission d&rsquo;\u00e9liminer Renfield. Tout l&rsquo;argent du monde ne prot\u00e8ge pas de l&rsquo;ire du Seigneur.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"1001\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-1.jpg\" alt=\"\" class=\"wp-image-6996\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-1.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-1-204x300.jpg 204w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Peru, Bianfantino, Nanjan &#8211; Oxymore<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Comme il l&rsquo;a fait pour les univers des Elfes et ses d\u00e9riv\u00e9es, apr\u00e8s l&rsquo;avoir lanc\u00e9, Jean-Luc Istin confie ce nouveau monde de West Fantasy a des sc\u00e9naristes dans lesquels il peut avoir toute confiance. Ces deux \u00e9pisodes sont \u00e9crits l&rsquo;un par Sylvain Corduri\u00e9, qui a contribu\u00e9 au d\u00e9veloppement du monde d&rsquo;Aquilon, l&rsquo;autre par Olivier Peru pour qui orcs et gobelins n&rsquo;ont pas de secrets non plus. Dans une unit\u00e9 de collection, les histoires sont chapitr\u00e9es et tournent autour de ces fameux totems myst\u00e9rieux donnant de la puissance. Dans chaque \u00e9pisode, un seul chapitre n&rsquo;est pas en BD mais en prose. C&rsquo;est chaque fois un passage capital et immanquable qui en apprend \u00e9norm\u00e9ment sur le pass\u00e9 de certains personnages, expliquant leurs destins.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"983\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-2.jpg\" alt=\"\" class=\"wp-image-6997\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-2.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-2-208x300.jpg 208w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Corduri\u00e9, Bordier, Nanjan \u2013 Oxymore<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Au dessin du tome 3, le fid\u00e8le Jean-Paul Bordier a un graphisme d&rsquo;une finesse irr\u00e9prochable. Regardez la biblioth\u00e8que des Anderson, la tranche de chacun des livres est d\u00e9finie. Pour le tome 4, d\u00e9j\u00e0 au g\u00e9n\u00e9rique d&rsquo;un tome d&rsquo;Aquilon, l&rsquo;italien Simone Buanfantino fait dans l&rsquo;explosif avec maestria.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"981\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-2.jpg\" alt=\"\" class=\"wp-image-6998\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-2.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-2-208x300.jpg 208w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Peru, Bianfantino, Nanjan &#8211; Oxymore<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La cr\u00e9ation de l&rsquo;univers West Fantasy est certainement l&rsquo;une des plus originales surprises de 2024. Un cinqui\u00e8me Tome va venir clore ce cycle qui, on l&rsquo;esp\u00e8re, ne sera que le premier d&rsquo;une longue s\u00e9rie.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"942\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3.jpg\" alt=\"\" class=\"wp-image-7000\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-3-217x300.jpg 217w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"836\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-3.jpg\" alt=\"\" class=\"wp-image-7001\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-3.jpg 600w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4-3-215x300.jpg 215w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie&nbsp;:<\/strong> West Fantasy<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tomes :<\/strong> 3 \u2013 L&rsquo;orc, le juge et le marshal \/ 4 \u2013 L&rsquo;orc, le banquier et l&rsquo;assassin<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre :<\/strong> H\u00e9ro\u00efc-Fantasy&nbsp;Western<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario :<\/strong> Sylvain Corduri\u00e9 \/ Olivier Peru<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins&nbsp;: <\/strong>Jean-Paul Bordier \/ Simone Buanfantino<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Couleurs :<\/strong> Nanjan<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Oxymore<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN :<\/strong> 9782385610-555\/-609<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>60<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 15,95 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>La loi du plus colt &nbsp;\u00ab\u00a0-Et le complice que vous m&rsquo;aviez promis pour m&rsquo;aider, o\u00f9 est-il ? -Justement ! M., voici Yaretsi. -Elle empeste l&rsquo;alcool et le tabac. -J&rsquo;\u00e9tais prise dans une partie de poker que je pouvais pas abandonner, et au poker, on boit et on fume, ma jolie ! On se contente pas &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2025\/01\/06\/west-fantasy-3-lorc-le-juge-et-le-marshal-4-lorc-le-banquier-et-lassassin\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0West Fantasy 3 \u2013 L&rsquo;orc, le juge et le marshal \/ 4 \u2013 L&rsquo;orc, le banquier et l&rsquo;assassin\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,17,458],"tags":[978],"class_list":["post-6993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-fantastique","category-western","tag-editions-oxymore"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2025\/01\/West-fantasy-4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=6993"}],"version-history":[{"count":2,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6993\/revisions"}],"predecessor-version":[{"id":7044,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6993\/revisions\/7044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/6999"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=6993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=6993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=6993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}