{"id":6849,"date":"2024-12-28T19:25:53","date_gmt":"2024-12-28T18:25:53","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=6849"},"modified":"2024-12-28T19:25:53","modified_gmt":"2024-12-28T18:25:53","slug":"darwins-incident-7","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2024\/12\/28\/darwins-incident-7\/","title":{"rendered":"Darwin\u2019s incident 7"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-5bfe7eca22f1b092d64cf3e68bba7213 wp-block-paragraph\"><strong>L&rsquo;heure de la confrontation<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/creators.spotify.com\/pod\/show\/laurent-lafourcade\/episodes\/Darwins-incident-7-e2smgrh\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/ebG_4wEc_qg\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-A mon avis, Omelas va forc\u00e9ment aller voir le professeur Grossman\u2026 pour se r\u00e9approprier son existence.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Oui. Pour commencer, on doit retourner \u00e0 New-York.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Charlie l&rsquo;humanzee et Lucy sont en planque apr\u00e8s avoir sem\u00e9 la police. Lucy est persuad\u00e9e qu&rsquo;Omelas, l\u2019autre humanzee, fr\u00e8re de Charlie, va aller voir le professeur Grossman, leur \u00ab\u00a0cr\u00e9ateur\u00a0\u00bb. Il va donc falloir qu&rsquo;ils retournent \u00e0 New-York\u2026 le plus discr\u00e8tement possible, en \u00e9vitant les barrages de police. Direction les bureaux de Galton. Et une fois l\u00e0-bas ? Ben, il n&rsquo;y aura plus qu&rsquo;\u00e0 kidnapper le PDG pour lui poser directement des questions sur Grossman. Le sh\u00e9rif adjoint Graham est invit\u00e9 \u00e0 faire sortir Charlie de sa cachette, mais il ne l&rsquo;entend pas de cette oreille. Le FBI ferait mieux de s&rsquo;occuper d&rsquo;Omelas et de tous ces enfoir\u00e9s de l&rsquo;ALA.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"1003\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-2.jpg\" alt=\"\" class=\"wp-image-6850\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-2.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-2-203x300.jpg 203w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2024 Shun Umezawa\/Kodansha Ltd.\u00a9 KANA 2024<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Lors d&rsquo;une conf\u00e9rence de presse, l&rsquo;homme d&rsquo;affaires Andrew Davenport, patron de Galton, d\u00e9nonce le terrorisme qui est en train de diviser l&rsquo;Am\u00e9rique. Il pr\u00f4ne le respect de la diversit\u00e9 et r\u00e9habilite Charlie en faisant de lui un h\u00e9ros. Ce n&rsquo;est pas un ennemi, ni lui, ni la technologie qui lui a donn\u00e9 naissance. Les technologies peuvent servir tout autant le bien que le mal. Tout d\u00e9pend de leur utilisation. En retournant \u00e0 son parking, Davenport est captur\u00e9. Charlie et Lucy qui viennent d&rsquo;arriver incognito dans la Grosse Pomme ont \u00e9t\u00e9 doubl\u00e9s. Les ennemis ayant le m\u00eame but, n&rsquo;ont-ils pas tous int\u00e9r\u00eat \u00e0 coop\u00e9rer pour interroger Grossman&nbsp;?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"1017\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-3.jpg\" alt=\"\" class=\"wp-image-6851\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-3.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-3-201x300.jpg 201w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2024 Shun Umezawa\/Kodansha Ltd.\u00a9 KANA 2024<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ce septi\u00e8me \u00e9pisode de Darwin\u2019s incident pr\u00e9sente un Charlie qui a bien l&rsquo;intention de reprendre la main. Les r\u00e9ponses \u00e0 ses questions, il les veut. Il est d\u00e9termin\u00e9. Bien s\u00fbr, il va se retrouver face \u00e0 son dieu-cr\u00e9ateur dans une sc\u00e8ne suspendue. Shun Umezawa arr\u00eate alors le temps et fait tout passer par les regards. La question que va poser l&rsquo;hybride au professeur r\u00e9sonne comme le tintement sourd du bourdon d&rsquo;une cloche. Cela prouve encore une fois que ce n&rsquo;est pas forc\u00e9ment dans les sc\u00e8nes d&rsquo;action que les plus grands mangakas r\u00e9v\u00e8lent leurs talents.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"993\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-4.jpg\" alt=\"\" class=\"wp-image-6852\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-4.jpg 680w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-4-205x300.jpg 205w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2024 Shun Umezawa\/Kodansha Ltd.\u00a9 KANA 2024<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;escalier en spirale que gravissent Charlie et Lucy en couverture est l&rsquo;all\u00e9gorie du tourbillon politique et d&rsquo;espionnage dans lequel ils se trouvent. Ces livres qui tombent semblent \u00eatre les manuels scientifiques renfermant les formules qui ont cr\u00e9\u00e9 les humanzees et qu&rsquo;il est impossible de saisir. Darwin&rsquo;s incident est le meilleur seinen du moment.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>Darwin\u2019s incident<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;: <\/strong>7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;: <\/strong>Anticipation<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario&nbsp;&amp; Dessins&nbsp;: <\/strong>Shun Umezawa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Kana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Collection : <\/strong>Big Kana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 978505126157<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>160<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 7,90 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;heure de la confrontation \u00ab\u00a0-A mon avis, Omelas va forc\u00e9ment aller voir le professeur Grossman\u2026 pour se r\u00e9approprier son existence. -Oui. Pour commencer, on doit retourner \u00e0 New-York.\u00a0\u00bb Charlie l&rsquo;humanzee et Lucy sont en planque apr\u00e8s avoir sem\u00e9 la police. Lucy est persuad\u00e9e qu&rsquo;Omelas, l\u2019autre humanzee, fr\u00e8re de Charlie, va aller voir le professeur Grossman, &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2024\/12\/28\/darwins-incident-7\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Darwin\u2019s incident 7\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,262,21],"tags":[309,144],"class_list":["post-6849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-manga","category-thriller-polar","tag-editions-kana","tag-manga"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/12\/Darwin7-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=6849"}],"version-history":[{"count":2,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6849\/revisions"}],"predecessor-version":[{"id":6887,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/6849\/revisions\/6887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/6853"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=6849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=6849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=6849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}