{"id":5483,"date":"2024-09-09T21:45:25","date_gmt":"2024-09-09T19:45:25","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=5483"},"modified":"2024-09-09T21:45:25","modified_gmt":"2024-09-09T19:45:25","slug":"nos-rives-partagees","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2024\/09\/09\/nos-rives-partagees\/","title":{"rendered":"Nos rives partag\u00e9es"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-800804b752a1fb2ec2a2c5f29178c16f wp-block-paragraph\"><strong>Par le prisme animal<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/6RnNC1vgLTlTxRti6whegI?si=257af26b312e4e85\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/CFEX2iZOagA\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Je ne comprends pas pourquoi tu t&rsquo;int\u00e9resses \u00e0 ces humains. Ils nous tuent avec leur mode de vie.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Je ne m&rsquo;int\u00e9resse pas aux humains. En tant qu&rsquo;esp\u00e8ce, ils me r\u00e9pugnent. C&rsquo;est la vie des sp\u00e9cimens qui sont install\u00e9s ici que je veux conna\u00eetre, les conna\u00eetre individuellement.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Pourquoi ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Ce sont nos voisins, c&rsquo;est important pour nous de les comprendre.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Mais pourquoi ceux-ci ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Pourquoi pas ? Le monde commence au pied de mon n\u00e9nuphar\u2026 Ces humains-l\u00e0 valent bien les autres.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les humains se plaisent \u00e0 regarder les animaux. Il \u00e9tait temps que vienne le tour de ces derniers pour observer les hommes, de s&rsquo;amuser \u00e0 les voir se d\u00e9battre dans leurs petites vies. C&rsquo;est ainsi que, tr\u00f4nant sur un n\u00e9nuphar, un crapaud charge chats, araign\u00e9es, oiseaux et autres biches d&rsquo;espionner la race des bip\u00e8des, juste pour savoir ce qu&rsquo;ils font. C&rsquo;est \u00e0 Dave Rivage, un village de la campagne belge, que les amours, les amiti\u00e9s et les soucis de gens ordinaires jouent leurs partitions devant les yeux des bestioles.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-752x1024.jpg\" alt=\"\" class=\"wp-image-5484\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-752x1024.jpg 752w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-220x300.jpg 220w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-768x1046.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-1128x1536.jpg 1128w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-1504x2048.jpg 1504w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-1-scaled.jpg 1880w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nicoby, Zabus, Ory &#8211; Dargaud<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hugo est un lyc\u00e9en dont le hobby est la photographie animale. Il initie sa camarade de classe Jill \u00e0 sa passion. Ils ne sont pas indiff\u00e9rents l&rsquo;un pour l&rsquo;autre. Qui fera le premier pas et jusqu&rsquo;o\u00f9 iront-ils ? Simon, le p\u00e8re de Hugo, est prof de fran\u00e7ais. En pleine correction d&rsquo;examens, les copies lui donnent envie de vomir, pas comme Diane, la femme qu&rsquo;il observe \u00e0 sa fen\u00eatre et qui a l&rsquo;habitude de se baigner dans la rivi\u00e8re, en toute discr\u00e9tion. Elle ne supporte pas les regards indiscrets et fait tout pour ne pas \u00eatre vue. Elle habite \u00e0 c\u00f4t\u00e9 de chez Pierre, l&rsquo;ancien amant de Nicole qui vient de temps en temps lui rendre visite. Pierre est en fauteuil roulant. Il a une maladie d\u00e9g\u00e9n\u00e9rative, vit en solitaire avec un perroquet, joue de la guitare et passe l&rsquo;essentiel de ses journ\u00e9es \u00e0 sa fen\u00eatre ouverte au rez-de-chauss\u00e9e.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-785x1024.jpg\" alt=\"\" class=\"wp-image-5485\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-785x1024.jpg 785w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-230x300.jpg 230w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-768x1002.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-1177x1536.jpg 1177w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-1570x2048.jpg 1570w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-2-scaled.jpg 1962w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nicoby, Zabus, Ory &#8211; Dargaud<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Vincent Zabus est un sc\u00e9nariste-po\u00e8te. Apr\u00e8s le sublime Mademoiselle Sophie et avant l&rsquo;\u00e9mouvant et sensible Les petits m\u00e9tiers m\u00e9connus, il livre ici une variation bucolique, analysant les sentiments humains avec une certaine r\u00eaverie. Lire un album sign\u00e9 Zabus, c&rsquo;est la garantie d&rsquo;\u00eatre touch\u00e9 dans son \u00e2me. Au dessin, le stakhanoviste Nicoby s&rsquo;accorde avec son camarade de jeu. Son trait jet\u00e9 a beaucoup plus de profondeur qu&rsquo;en apparence. Les culs-de-lampe des chapitres et quelques clich\u00e9s de Hugo sont en couleurs crayonn\u00e9es montrant une autre facette de son talent. Saluons les couleurs de Philippe Ory, simples et belles, qui vient de nous quitter.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-783x1024.jpg\" alt=\"\" class=\"wp-image-5486\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-783x1024.jpg 783w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-229x300.jpg 229w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-768x1004.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-1175x1536.jpg 1175w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-1566x2048.jpg 1566w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-3-scaled.jpg 1958w\" sizes=\"auto, (max-width: 783px) 100vw, 783px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nicoby, Zabus, Ory &#8211; Dargaud<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hugo\/Jill, Simon\/Diane, Pierre\/Nicole, trois histoires de s\u00e9ductions s&rsquo;entrecroisent sous les yeux des animaux\u2026 parce qu&rsquo;ils partagent la m\u00eame rive. Cela permettra-t-il aux uns comme aux autres de comprendre la vie ? Inexplicablement fascinant.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>One shot : <\/strong>Nos rives partag\u00e9es<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Emotion<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario : <\/strong>Vincent Zabus<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins : <\/strong>Nicoby<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Couleurs :<\/strong> Philippe Ory<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Dargaud<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 9782205212099<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>160<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 22 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Par le prisme animal \u00ab\u00a0-Je ne comprends pas pourquoi tu t&rsquo;int\u00e9resses \u00e0 ces humains. Ils nous tuent avec leur mode de vie. -Je ne m&rsquo;int\u00e9resse pas aux humains. En tant qu&rsquo;esp\u00e8ce, ils me r\u00e9pugnent. C&rsquo;est la vie des sp\u00e9cimens qui sont install\u00e9s ici que je veux conna\u00eetre, les conna\u00eetre individuellement. -Pourquoi ? -Ce sont nos &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2024\/09\/09\/nos-rives-partagees\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Nos rives partag\u00e9es\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":5487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,18],"tags":[187],"class_list":["post-5483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-emotion","tag-editions-dargaud"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/09\/Nos-rives-partages-couv.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/5483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=5483"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/5483\/revisions"}],"predecessor-version":[{"id":5488,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/5483\/revisions\/5488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/5487"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=5483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=5483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=5483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}