{"id":4646,"date":"2024-04-20T13:55:25","date_gmt":"2024-04-20T11:55:25","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=4646"},"modified":"2024-04-20T13:55:25","modified_gmt":"2024-04-20T11:55:25","slug":"quand-la-nuit-tombe-1-lisou","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2024\/04\/20\/quand-la-nuit-tombe-1-lisou\/","title":{"rendered":"Quand la nuit tombe 1 \u2013 Lisou"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-e17d91c24cdd5ab9da45455efed86ecd wp-block-paragraph\"><strong>Les chats et les souris<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/1nZBPHBlzmxYZBYHiq9ePD?si=fd25f5016220484b\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/BlqvQDzgrF8\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-La Gestapo a cern\u00e9 le centre du village. Ces ordures ont fouill\u00e9 toutes les maisons ! Il para\u00eet qu&rsquo;ils retrouvaient les Juifs cach\u00e9s en demandant aux commer\u00e7ants les adresses de leur client\u00e8le ! Ils ont embarqu\u00e9 une vingtaine de familles.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Une vingtaine de familles ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Les hommes ont travers\u00e9 la ville en marchant les bras lev\u00e9s, et les femmes tenaient leur enfant d&rsquo;une main et leur baluchon de l&rsquo;autre\u2026<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Mais Henri, o\u00f9 les ont-ils emmen\u00e9s ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Je ne suis s\u00fbr de rien. Tr\u00e8s probablement au si\u00e8ge de la Gestapo, ou d\u00e9j\u00e0 \u00e0 Drancy\u2026 ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Que deviennent tous ces pauvres gens ?\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Janvier 2022, Marion prend un caf\u00e9 avec sa tante Lisou, 89 ans. Carnet de notes sur les genoux, Marion l&rsquo;interroge sur sa vie pendant la Seconde Guerre Mondiale. En juin 1940, la famille juive quitte sa Lorraine pour le sud de la France \u00e0 cause de l&rsquo;invasion allemande. Apr\u00e8s un passage dans l&rsquo;Indre, puis \u00e0 Grenoble, voici Lisou, sa s\u0153ur Mylaine et leurs parents r\u00e9fugi\u00e9s \u00e0 Sarcenas, un petit village \u00e0 douze kilom\u00e8tres de la pr\u00e9fecture de l&rsquo;Is\u00e8re. La chasse aux juifs a commenc\u00e9, il faut se cacher. Lisou a dix ans et la guerre n&rsquo;en finit plus de finir. Ils trouvent asile dans un chalet pr\u00eat\u00e9 par des amis. Les mois et les saisons se succ\u00e8dent. Les nazis se d\u00e9cha\u00eenent dans la r\u00e9gion. Les rafles font rage. Un jour neigeux de f\u00e9vrier 1944, alors que les parents sont partis raccompagner des amis jusqu&rsquo;\u00e0 l&rsquo;autocar de Sappey, les deux jeunes filles voient d\u00e9barquer une automobile noire. Ils recherchent la famille. Mylaine ment sur leur identit\u00e9 et leur indique une maison voisine. Les boches tournent les talons. La grande envoie sa petite s\u0153ur pr\u00e9venir les parents pour qu&rsquo;ils ne rentrent pas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-751x1024.jpg\" alt=\"\" class=\"wp-image-4647\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-751x1024.jpg 751w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-220x300.jpg 220w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-768x1047.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-1127x1536.jpg 1127w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-1503x2048.jpg 1503w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-1-scaled.jpg 1879w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Achard, Galm\u00e9s &#8211; Delcourt<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Mylaine sera arr\u00eat\u00e9e par les nazis, Lisou et ses parents erreront de cachettes en cachettes pour leur \u00e9chapper. Mylaine et Lisou sont aujourd&rsquo;hui en vie. Ce sont les tantes de la sc\u00e9nariste Marion Achard. Elle les a longuement interrog\u00e9es en 2021. A 88 et 98 ans, elles ont apport\u00e9 leurs t\u00e9moignages sur cette p\u00e9riode barbare d&rsquo;un si\u00e8cle faussement civilis\u00e9. Elles ont montr\u00e9 \u00e0 leur ni\u00e8ce les fausses cartes d&rsquo;identit\u00e9, les diff\u00e9rents courriers conserv\u00e9s, \u00e9chang\u00e9s entre eux, ou ceux de d\u00e9nonciation et de la Gestapo. Marion Achard en a tir\u00e9 le sc\u00e9nario de ce diptyque inspir\u00e9 de leurs vies, de leurs destins bris\u00e9s. La fillette et l&rsquo;adolescente seront s\u00e9par\u00e9es par la trag\u00e9die. Cet \u00e9pisode suit les pas de Lisou. Le second nous emm\u00e8nera sur les traces de Mylaine et nous fera vivre sa d\u00e9portation. On sait d\u00e9j\u00e0 qu&rsquo;elles se retrouveront. \u00c7a va l\u00e9g\u00e8rement aider \u00e0 supporter le drame.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-773x1024.jpg\" alt=\"\" class=\"wp-image-4648\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-773x1024.jpg 773w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-226x300.jpg 226w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-768x1018.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-1159x1536.jpg 1159w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-1545x2048.jpg 1545w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-2-scaled.jpg 1932w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Achard, Galm\u00e9s &#8211; Delcourt<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La volont\u00e9 de Marion, d\u00e8s le d\u00e9part, est de s&rsquo;adresser aux adolescents, parce que l&rsquo;avenir du monde est dans leurs mains. Il faut se souvenir pour ne pas reproduire les erreurs du pass\u00e9. C&rsquo;est tellement bateau, cette phrase, mais c&rsquo;est tellement vrai, tellement important. Dans un trait tout public arrondi, \u00e0 la mani\u00e8re d&rsquo;un Beno\u00eet Ers, Toni Galmes dessine l&rsquo;ensemble avec l&rsquo;innocence de Lisou toujours en ligne de mire. Ce n&rsquo;est pas une h\u00e9ro\u00efne, ce n&rsquo;est pas une observatrice, C&rsquo;est l&rsquo;actrice d&rsquo;une p\u00e9riode trouble. Tout au long du r\u00e9cit, on est \u00ab\u00a0elle\u00a0\u00bb, au jour le jour.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-734x1024.jpg\" alt=\"\" class=\"wp-image-4649\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-734x1024.jpg 734w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-215x300.jpg 215w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-768x1072.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-1101x1536.jpg 1101w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-1468x2048.jpg 1468w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-la-nuit-tombe-3-scaled.jpg 1834w\" sizes=\"auto, (max-width: 734px) 100vw, 734px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Achard, Galm\u00e9s &#8211; Delcourt<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A ranger aux c\u00f4t\u00e9s des Enfants de la R\u00e9sistance, Quand la nuit tombe (quel titre efficace !) d\u00e9montre encore une fois d&rsquo;une part aux t\u00e9moins de l&rsquo;\u00e9poque que raconter leur histoire est la clef pour que la nuit ne retombe plus, et d&rsquo;autre part aux lecteurs d&rsquo;aujourd&rsquo;hui qu&rsquo;il est des temps sombres qui ne doivent pas revenir.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>Quand la nuit tombe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;: <\/strong>1 \u2013 Lisou<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Histoire<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario : <\/strong>Marion Achard<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins&nbsp;&amp; Couleurs : <\/strong>Toni Galm\u00e9s<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Delcourt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Collection :<\/strong> Histoire et histoires<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 9782413077657<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>128<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 19,99 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Les chats et les souris \u00ab\u00a0-La Gestapo a cern\u00e9 le centre du village. Ces ordures ont fouill\u00e9 toutes les maisons ! Il para\u00eet qu&rsquo;ils retrouvaient les Juifs cach\u00e9s en demandant aux commer\u00e7ants les adresses de leur client\u00e8le ! Ils ont embarqu\u00e9 une vingtaine de familles. -Une vingtaine de familles ? -Les hommes ont travers\u00e9 la &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2024\/04\/20\/quand-la-nuit-tombe-1-lisou\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Quand la nuit tombe 1 \u2013 Lisou\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,25,186],"tags":[34],"class_list":["post-4646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-histoire","category-vie-vecue","tag-editions-delcourt"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/04\/Quand-na-nuit-tombe-1-couv.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=4646"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions"}],"predecessor-version":[{"id":4651,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions\/4651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/4650"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=4646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=4646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=4646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}