{"id":4318,"date":"2024-03-09T00:37:24","date_gmt":"2024-03-08T23:37:24","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=4318"},"modified":"2024-03-09T00:37:24","modified_gmt":"2024-03-08T23:37:24","slug":"demain-tintin","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2024\/03\/09\/demain-tintin\/","title":{"rendered":"Demain Tintin ?"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-37466326614bb9026b45ef74dd7a267d wp-block-paragraph\"><strong>Entretien avec \u00ab\u00a07 fils de Tintin\u00a0\u00bb<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/5bDJ38GNwnrKXggzaAWdom?si=7876af4c9d0a4bf4\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/aAmE8lJABNw\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0M\u00eame s&rsquo;il n&rsquo;existait que Tintin, la bande dessin\u00e9e serait justifi\u00e9e comme art.\u00a0\u00bb (Beno\u00eet Peeters)<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Nous avons tous en nous quelque chose d&rsquo;Herg\u00e9, de sa ligne claire, claire et \u00e9clairante, belle \u00e9toile.\u00a0\u00bb Cette d\u00e9claration d&rsquo;Hubert V\u00e9drine, ancien ministre des Affaires \u00e9trang\u00e8res, en pr\u00e9face, est indiscutable. Si l&rsquo;\u0153uvre du ma\u00eetre a marqu\u00e9 tant de g\u00e9n\u00e9rations, c&rsquo;est qu&rsquo;elle a quelque chose d&rsquo;universel et de magique qui atteint tout lecteur en son for int\u00e9rieur. On peut quitter Tintin. On y revient avec le m\u00eame plaisir. 600 ! 600, c&rsquo;est le nombre du jour. Plus de 600 ouvrages ont d\u00e9j\u00e0 \u00e9t\u00e9 consacr\u00e9s \u00e0 Herg\u00e9 et \u00e0 son \u0153uvre. Alors, pourquoi Renaud Nattiez, \u00e9minent tintinologue, en publie-t-il un de plus ? Tout simplement parce que, pour la premi\u00e8re fois, l&rsquo;avenir de Tintin est abord\u00e9. Si dans son ouvrage pr\u00e9c\u00e9dent \u00ab\u00a0Faut-il br\u00fbler Tintin ?\u00a0\u00bb, Renaud Nattiez d\u00e9montrait qu&rsquo;il y avait toujours quelque chose \u00e0 dire sur le sujet, il questionne ici sept fils de Tintin, sept sp\u00e9cialistes de l&rsquo;univers, sur la p\u00e9rennit\u00e9 de l&rsquo;\u0153uvre. Les ventes des albums sont en baisse. Alors que le dernier album achev\u00e9 est paru en 1976, il y a quarante-huit ans, Tintin peut-il r\u00e9sister \u00e0 la concurrence ? Int\u00e9resse-t-il encore les jeunes lecteurs ?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"621\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-621x1024.jpg\" alt=\"\" class=\"wp-image-4319\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-621x1024.jpg 621w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-182x300.jpg 182w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-768x1266.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-932x1536.jpg 932w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-1243x2048.jpg 1243w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-1-scaled.jpg 1554w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nattiez \u2013 1000 sabords<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le grand interrogatoire d\u00e9bute avec Albert Algoud, qui a sign\u00e9 l&rsquo;un des best-seller sur le sujet : Le Haddock illustr\u00e9, dictionnaire des jurons du Capitaine. Il n&rsquo;a jamais \u00e9crit d&rsquo;ouvrages d&rsquo;analyse sur l&rsquo;\u0153uvre elle-m\u00eame, mais s&rsquo;est attach\u00e9 aux personnages avec notamment des biographies de Bianca Castafiore et du Senhor Oliveira da Figueira. Pour lui, qu&rsquo;importe si Tintin est et sera moins lu par les jeunes. Son auteur restera un grand artiste. Il voit la p\u00e9rennit\u00e9 du personnage dans l&rsquo;imaginaire des foules gr\u00e2ce \u00e0 toutes formes de d\u00e9tournements artistiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auteur de Tintin et le mythe du Surenfant, l&rsquo;universitaire Jean-Marie Apostolid\u00e8s disparu il y a juste un an avait une vision plus pessimiste, pensant que la notori\u00e9t\u00e9 de Tintin dispara\u00eetra avec sa g\u00e9n\u00e9ration qui est celle de tous les sp\u00e9cialistes interrog\u00e9s ici. Pourtant, il affirme qu&rsquo;il y a encore \u00e0 dire sur le sujet, citant Bertrand M\u00e9heust dont les recherches pourraient aboutir sur une nouvelle approche de Tintin, o\u00f9 il est question de m\u00e9tapsychisme et de m\u00e9diumnit\u00e9. C&rsquo;est ensuite au tour de Pierre Assouline, auteur d&rsquo;une biographie d\u00e9taill\u00e9e d&rsquo;Herg\u00e9 en 1996, de s&rsquo;exprimer. Lui, voit le dessin anim\u00e9 et ses rediffusions comme moyen de perp\u00e9trer l&rsquo;\u0153uvre, plus que le cin\u00e9ma. Assouline a connu Tchang. Il pense qu&rsquo;il y a encore des choses \u00e0 dire sur l&rsquo;\u0153uvre mais qu&rsquo;il ne faut pas tomber dans la sp\u00e9culation et les \u00e9lucubrations.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-604x1024.jpg\" alt=\"\" class=\"wp-image-4321\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-604x1024.jpg 604w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-177x300.jpg 177w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-768x1303.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-905x1536.jpg 905w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-1207x2048.jpg 1207w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-3-scaled.jpg 1509w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nattiez \u2013 1000 sabords<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En milieu d&rsquo;ouvrage, voici l&rsquo;entretien avec Philippe Goddin. Biographe et ami d&rsquo;Herg\u00e9, secr\u00e9taire g\u00e9n\u00e9ral pendant dix ans de la Fondation Herg\u00e9, pr\u00e9sident de l&rsquo;association Les amis de Herg\u00e9, il est certainement l&rsquo;analyste le plus l\u00e9gitime qui soit. Avec lui, Renaud Nattiez peut se permettre d&rsquo;aller encore plus loin qu&rsquo;avec les autres questionn\u00e9s. Continuer \u00e0 faire vivre Tintin sans nouveaut\u00e9s est une gageure. Il n&rsquo;est pas contre une vision parall\u00e8le comme a pu le faire Emile Bravo avec Spirou. Mais on marche sur des \u0153ufs. Quant aux ouvrages d&rsquo;analyse, Goddin avoue avoir \u00e9crit sur Tintin et le Thermo-Z\u00e9ro\u2026en attendant \u00ab\u00a0une marque d&rsquo;int\u00e9r\u00eat de la part de Nick Rodwell.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jacques Langlois prend la suite. Ayant correspondu avec Herg\u00e9, l&rsquo;auteur du Petit \u00e9loge de Tintin se positionne en tant qu&rsquo;observateur. Il partage avec Nattiez l&rsquo;objectif de lire et de relire Tintin, avant tout pour le plaisir. Langlois s&rsquo;interroge sur l&rsquo;int\u00e9r\u00eat de la parution d&rsquo;un nouvel album en 2054, lorsque le h\u00e9ros sera tomb\u00e9 dans le domaine public, alors que le gros des tintinophiles aura disparu.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-598x1024.jpg\" alt=\"\" class=\"wp-image-4322\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-598x1024.jpg 598w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-175x300.jpg 175w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-768x1316.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-896x1536.jpg 896w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-1195x2048.jpg 1195w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-4-scaled.jpg 1494w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nattiez \u2013 1000 sabords<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Auteur de la premi\u00e8re monographie Le monde d&rsquo;Herg\u00e9, parue fin 1983, ann\u00e9e du d\u00e9c\u00e8s de l&rsquo;auteur, le pointilleux Beno\u00eet Peeters encha\u00eene, voit en l&rsquo;absence de nouvel album la force du mythe. Il partage avec Aspotolid\u00e8s l&rsquo;\u00e9mergence possible d&rsquo;une ex\u00e9g\u00e8se originale. Paradoxalement, mais n&rsquo;est-ce pas lui qui aurait raison, ayant grandi avec le reporter \u00e0 houppe, Peeters ne s&rsquo;estime pas l\u00e9gitime pour parler de son avenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les rendez-vous de Renaud Nattiez se concluent avec Numa Sadoul. Il est l&rsquo;auteur de deux des plus grands livres de r\u00e9f\u00e9rence sur le 9<sup>\u00e8me<\/sup> Art : Et Franquin cr\u00e9a la gaffe, et Entretiens avec Herg\u00e9, publi\u00e9 pour la premi\u00e8re fois en 1975. Lui, est clairement pour la sortie d&rsquo;un nouvel album, mais, \u00e0 l&rsquo;instar de ce que pr\u00e9conise Goddin, avec une vision d&rsquo;auteurs qui projetteraient leur univers sans d\u00e9naturer l&rsquo;original.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"647\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-647x1024.jpg\" alt=\"\" class=\"wp-image-4320\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-647x1024.jpg 647w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-190x300.jpg 190w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-768x1215.jpg 768w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-971x1536.jpg 971w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-1294x2048.jpg 1294w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-2-scaled.jpg 1618w\" sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Nattiez \u2013 1000 sabords<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cette chronique n&rsquo;est que le survol d&rsquo;un ouvrage qui porte \u00e0 r\u00e9flexion. Au fil des entretiens, on s&rsquo;amuse \u00e0 imaginer les r\u00e9ponses que l&rsquo;on aurait apport\u00e9 soi-m\u00eame aux questions pertinentes de Renaud Nattiez dont il ne manquerait dans ce livre que l&rsquo;auto-entretien. Pour une rencontre avec lui, je vous invite \u00e0 vous rendre sur le site et la cha\u00eene YouTube Boulevard BD pour un grand entretien film\u00e9 et illustr\u00e9 avec lui. Pour en finir avec ce \u00ab\u00a0Demain Tintin ?\u00a0\u00bb (mais rien n&rsquo;est jamais fini avec Herg\u00e9 et Tintin) , Olivier Roche, r\u00e9dacteur en chef de l&rsquo;indispensable Houpette Lib\u00e9r\u00e9e, signe une postface r\u00e9sumant le propos. Il demande explicitement \u00e0 Tintinimaginatio, soci\u00e9t\u00e9 des ayant-droits g\u00e9rant l&rsquo;\u0153uvre, d&rsquo;ouvrir ses portes aux sp\u00e9cialistes et aux artistes. Ce sont eux qui ont les clefs de ce que sera Tintin demain. En attendant, quand on a fini de lire Tintin, on peut recommencer \u00e0 lire Tintin. On y trouvera toujours quelque chose de nouveau.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>One shot&nbsp;: <\/strong>Demain Tintin ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Entretiens<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Auteur : <\/strong>Renaud Nattiez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> 1000 sabords<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;: <\/strong>9782494744127<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>184<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 20 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Entretien avec \u00ab\u00a07 fils de Tintin\u00a0\u00bb \u00ab\u00a0M\u00eame s&rsquo;il n&rsquo;existait que Tintin, la bande dessin\u00e9e serait justifi\u00e9e comme art.\u00a0\u00bb (Beno\u00eet Peeters) \u00ab\u00a0Nous avons tous en nous quelque chose d&rsquo;Herg\u00e9, de sa ligne claire, claire et \u00e9clairante, belle \u00e9toile.\u00a0\u00bb Cette d\u00e9claration d&rsquo;Hubert V\u00e9drine, ancien ministre des Affaires \u00e9trang\u00e8res, en pr\u00e9face, est indiscutable. Si l&rsquo;\u0153uvre du ma\u00eetre a &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2024\/03\/09\/demain-tintin\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Demain Tintin ?\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,93,113,878],"tags":[864,116,117],"class_list":["post-4318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-classique-chroniques","category-ouvrage-detude","category-tintin","tag-editions-1000-sabords","tag-herge","tag-tintin"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/03\/Demain-Tintin-couv.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=4318"}],"version-history":[{"count":2,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4318\/revisions"}],"predecessor-version":[{"id":4331,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/4318\/revisions\/4331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/4323"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=4318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=4318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=4318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}