{"id":3799,"date":"2024-01-07T22:47:56","date_gmt":"2024-01-07T21:47:56","guid":{"rendered":"http:\/\/boulevardbd.com\/?p=3799"},"modified":"2024-01-07T22:47:56","modified_gmt":"2024-01-07T21:47:56","slug":"la-bande-dessinee-en-afrique-a-lepoque-coloniale","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2024\/01\/07\/la-bande-dessinee-en-afrique-a-lepoque-coloniale\/","title":{"rendered":"La bande dessin\u00e9e en Afrique \u00e0 l&rsquo;\u00e9poque coloniale"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Un art sous contraintes<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/1KoXVpc31fMkOtQPH3YR7Z?si=42b0b3fdbc824782\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/7cFhkPmZJW4\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Eh bien ! Que t&rsquo;arrive-t-il ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Koumba\u2026 Elle est disparue. Vite, il faut que tu ailles voir son p\u00e8re.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Si la bande dessin\u00e9e a plus de cent ans d&rsquo;existence en Afrique, c&rsquo;est parce que son apparition co\u00efncide avec l&rsquo;arriv\u00e9e des colons europ\u00e9ens. Pourtant, il existait d\u00e9j\u00e0 dans les civilisations indig\u00e8nes une culture de l&rsquo;image et du r\u00e9cit imag\u00e9. Les colons vont se servir de ce medium pour faire passer des messages \u00e9ducatifs, propagandistes et pr\u00e9ceptifs aux populations locales. Les envahisseurs vont ainsi impulser et contr\u00f4ler les connaissances inculqu\u00e9es de leur conception \u00e0 leur diffusion. C\u00f4t\u00e9 francophone (les colons \u00e9tant aussi anglophones ou lusophones), il n&rsquo;y eut aucun soutien \u00e0 l&rsquo;\u00e9dition locale en Afrique Noire. Hormis ce qui venait de Madagascar, tout \u00e9tait import\u00e9 de France. Et s&rsquo;ils \u00e9taient fabriqu\u00e9s sur place, c&rsquo;\u00e9taient des manuels \u00e9crits par des fonctionnaires fran\u00e7ais.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"554\" height=\"959\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-3.jpg\" alt=\"\" class=\"wp-image-3802\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-3.jpg 554w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-3-173x300.jpg 173w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 L&rsquo;Harmattan BD<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; L&rsquo;essai de Christophe Cassiau-Haurie et de Christophe Meunier s&rsquo;articule autour de trois p\u00e9riodes : l&rsquo;introduction de la bande dessin\u00e9e pendant la colonisation, le c\u0153ur des conflits mondiaux, de la Premi\u00e8re \u00e0 la Seconde Guerre mondiale, montrant \u00e0 l&rsquo;Afrique que l&rsquo;homme blanc pouvait vaciller et o\u00f9 les d\u00e9sirs d&rsquo;ind\u00e9pendance se font ressentir, puis le d\u00e9but des \u00e9mancipations apr\u00e8s 1945 et jusqu&rsquo;aux ann\u00e9es 60, \u00e0 quelques ann\u00e9es pr\u00e8s pour certaines exceptions. L&rsquo;Entre-Deux-Guerres et la d\u00e9colonisation verront l&rsquo;\u00e9mergence de dessinateurs locaux qui travailleront pour la presse locale et cr\u00e9eront quelques personnages r\u00e9currents. Revenons sur chacun de ces chapitres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avant la Premi\u00e8re Guerre Mondiale, se d\u00e9veloppe donc la bande dessin\u00e9e en Afrique en tant qu&rsquo;instrument de colonisation. \u00c7a ne fait pas si longtemps que Rodolphe T\u00f6pffer a invent\u00e9 ce nouveau langage entre la litt\u00e9rature et le graphisme. N\u00e9 en 1887, le camerounais Ibrahim Njoya se fait remarquer en ex\u00e9cutant des dessins sur le sable avant de rentrer \u00e0 la cour du sultan o\u00f9 il fera des dessins sur papier. Il r\u00e9alisa de v\u00e9ritables histoires illustr\u00e9es comme La rate et les quatre ratons en 1940. En Egypte, c&rsquo;est d\u00e8s la fin du XIX<sup>\u00e8me<\/sup> si\u00e8cle que l&rsquo;on peut lire les premiers cartoons, \u00e0 l&rsquo;\u00e9poque, c&rsquo;\u00e9tait des caricatures proches de la BD. James Yaqub Sanua en \u00e9tait l&rsquo;un des fers de lance. Sur l&rsquo;\u00cele Maurice et \u00e0 la R\u00e9union, les journaux satiriques font la part belle aux railleries. Le Voyage de M.Chose dans la mer des Indes, par Antoine Roussin en t\u00e9moigne. Les treize planches sont reproduites dans cet essai. Le chapitre se cl\u00f4t sur la situation en Afrique du Sud-Est avec les cartoonistes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"548\" height=\"963\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-2-Personnalise.jpg\" alt=\"\" class=\"wp-image-3800\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-2-Personnalise.jpg 548w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-2-Personnalise-171x300.jpg 171w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 L&rsquo;Harmattan BD<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La deuxi\u00e8me partie s&rsquo;arr\u00eate sur le d\u00e9veloppement de la presse coloniale de 1918 \u00e0 1945. En Afrique belge et notamment au Katanga, les dessins humoristiques racistes de Sav rencontrent un certain succ\u00e8s. Les auteurs reviennent sur l&rsquo;influence des P\u00e8res blancs missionnaires. On apprend que Paul Lomami serait l&rsquo;un des premiers \u00e9crivains dessinateurs congolais avec Le match de Jako et Mako paru dans La Croix du Congo en 1933. Il est aussi \u00e9videmment question de Tintin au Congo. On passe ensuite en Afrique Noire fran\u00e7aise, en particulier au S\u00e9n\u00e9gal, avant de regagner l&rsquo;Afrique du Nord o\u00f9 arrivent les productions francophones. Le cas de ce qui se passe en Egypte est fort int\u00e9ressant \u00e0 observer avec la revue Al-Awlad publiant aussi bien des productions locales originales que des r\u00e9appropriations de Mickey. On finit par un crochet vers l&rsquo;Union Sud-Africaine o\u00f9 la population blanche fortement pr\u00e9sente entra\u00eene le d\u00e9veloppement de la presse, avec des bandes dessin\u00e9es au format anglo-saxons plut\u00f4t abouties.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La partie trois est consacr\u00e9e \u00e0 l&rsquo;ind\u00e9pendance africaine et \u00e0 la fa\u00e7on dont les africains se sont empar\u00e9s de la bande dessin\u00e9e entre 1945 et 1970. Les auteurs locaux \u00e9mergent aux c\u00f4t\u00e9s de dessinateurs francophones confirm\u00e9s comme Bara, Follet ou Azara. Au Maghreb, \u00e9galement aussi bien au Congo qu&rsquo;au Rwanda, des magazines connaissent leurs heures de gloire. Une autre partie du continent restera sous influence britannique. L&rsquo;Oc\u00e9an Indien et l&rsquo;Afrique lusophone ne seront pas en reste.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"968\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-4.jpg\" alt=\"\" class=\"wp-image-3803\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-4.jpg 563w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-4-174x300.jpg 174w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 L&rsquo;Harmattan BD<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Christophe Cassiau-Haurie et Christophe Meunier d\u00e9montrent dans cet essai l&rsquo;influence de la colonisation sur le d\u00e9veloppement de la bande dessin\u00e9e en Afrique. Il est judicieux de le lire parall\u00e8lement \u00e0 <em>Herg\u00e9, Franquin, le chevalier et le missionnaire<\/em>, de Philippe Delisle, paru chez PLG. L&rsquo;\u00e9poque coloniale est bien r\u00e9volue. Des productions contemporaines montrent leur d\u00e9tachement par rapport \u00e0 la BD franco-belge. Mais \u00e7a, c&rsquo;est une autre histoire.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>One shot&nbsp;: <\/strong>La bande dessin\u00e9e en Afrique \u00e0 l&rsquo;\u00e9poque coloniale<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Ouvrage d&rsquo;\u00e9tude<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Auteur : <\/strong>Christophe Cassiau-Haurie et Christophe Meunier<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> L&rsquo;Harmattan BD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Collection : <\/strong>S\u00e9rie essais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;: <\/strong>9782140496172<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>176<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 20 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Un art sous contraintes \u00ab\u00a0-Eh bien ! Que t&rsquo;arrive-t-il ? -Koumba\u2026 Elle est disparue. Vite, il faut que tu ailles voir son p\u00e8re.\u00a0\u00bb &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Si la bande dessin\u00e9e a plus de cent ans d&rsquo;existence en Afrique, c&rsquo;est parce que son apparition co\u00efncide avec l&rsquo;arriv\u00e9e des colons europ\u00e9ens. Pourtant, il existait d\u00e9j\u00e0 dans les civilisations indig\u00e8nes &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2024\/01\/07\/la-bande-dessinee-en-afrique-a-lepoque-coloniale\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0La bande dessin\u00e9e en Afrique \u00e0 l&rsquo;\u00e9poque coloniale\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,113],"tags":[759,149,847,117],"class_list":["post-3799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-ouvrage-detude","tag-afrique","tag-colonisation","tag-editions-lharmattan-2","tag-tintin"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2024\/01\/La-bande-dessinee-en-Afrique-1.jpg","_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=3799"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3799\/revisions"}],"predecessor-version":[{"id":3805,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3799\/revisions\/3805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/3804"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=3799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=3799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=3799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}