{"id":3405,"date":"2023-12-02T23:30:48","date_gmt":"2023-12-02T22:30:48","guid":{"rendered":"http:\/\/boulevardbd.com\/?p=3405"},"modified":"2023-12-02T23:30:48","modified_gmt":"2023-12-02T22:30:48","slug":"ucc-dolores-5-les-sables-de-tishala","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2023\/12\/02\/ucc-dolores-5-les-sables-de-tishala\/","title":{"rendered":"UCC Dolores 5 \u2013 Les sables de Tishala\u00a0"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-a1edbd8d655405adeea39bca52d33cc7 wp-block-paragraph\"><strong>Mad Mony<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/4wI8cCCmgRKs8SEOcqc5VT?si=c10683184fed4434\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/KLJEWrD9-N8\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Impressionnant ! Tu es vraiment \u00e0 la hauteur de ta r\u00e9putation.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Joli jouet, mais il tire trop sur la droite\u2026 de trois degr\u00e9s. Je suppose que j&rsquo;ai r\u00e9ussi votre test. Je viens, mais avec mon mat\u00e9riel.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Ha ! Ha ! S&rsquo;il n&rsquo;y a que \u00e7a !&#8230; Mes chiens, je vous annonce que nous aurons parmi nous la redoutable Main-Rouge.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Joli tir !<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-Ouais, et jolie chienne !\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Mais pourquoi donc Mony cherche-t-elle \u00e0 int\u00e9grer un groupe de mercenaires sauvages ? Les mercenaires de Centauri, les sans-visages d&rsquo;Estellos, les fr\u00e8res Slouguy de Bastanar et les \u00e9corcheurs de Passoriio font tous partie de ces chasseurs. Un million de dolbards, c&rsquo;est ce que propose \u00e0 Mony le chef du groupe, le capitaine Sharkis. Mony a besoin d&rsquo;argent pour r\u00e9parer son vaisseau l&rsquo;UCC Dolores et ainsi quitter cette plan\u00e8te toxique. Sa fille Lune est malade. Elle est sous respirateur. Ses poumons sont rong\u00e9s par la pollution. Ils ne vont pas pouvoir rester longtemps ici. Ce serait fatal pour la petite.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"797\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-2.jpg\" alt=\"\" class=\"wp-image-3406\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-2.jpg 600w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-2-226x300.jpg 226w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Tarquin, Tarquin &#8211; Gl\u00e9nat<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u00c7a fait cinq ans que Mony et ses camarades d&rsquo;infortune sont bloqu\u00e9s sur Tishala. Tuco pense que Mony s&#8217;embarque dans un contrat bien dangereux. Il lui installe dans son bras bionique un flasheur qui lui permettra de se d\u00e9fendre. Sha\u00ebl lui promet qu&rsquo;il prendra soin de Lune s&rsquo;il lui arrive malheur. C&rsquo;est parti pour une exp\u00e9dition au-del\u00e0 des territoires interdits afin d&rsquo;affronter les racleurs de carcasses, la tribu des invisibles. Ce que la guerri\u00e8re farouche ne sait pas encore c&rsquo;est que Sharkis a les moyens de la garder dans son giron, co\u00fbte que co\u00fbte.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"797\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-3.jpg\" alt=\"\" class=\"wp-image-3407\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-3.jpg 600w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-3-226x300.jpg 226w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Tarquin, Tarquin &#8211; Gl\u00e9nat<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Avec un bond dans le temps de plusieurs ann\u00e9es, la saga de l&rsquo;UCC Dolores prend une nouvelle tournure. D\u00e9cid\u00e9ment, les Tarquin ne m\u00e9nagent pas leur h\u00e9ro\u00efne dans un monde o\u00f9 le lecteur avis\u00e9 d\u00e9c\u00e8lera de nombreux clins d&rsquo;\u0153il \u00e0 la culture geek des ann\u00e9es 80. On a d\u00e9j\u00e0 parl\u00e9 du c\u00f4t\u00e9 Cosmocat de Sha\u00ebl. On est clairement dans un d\u00e9cor \u00e0 la Mad max. Le bras de Mony n&rsquo;est pas sans rappeler sous une autre forme celui d&rsquo;un certain Cobra. Quant \u00e0 Sharkis et son double visage, c&rsquo;est un hommage av\u00e9r\u00e9 au commandant du camp de la Lune Noire des forces de Vega, un certain Minos dans Goldorak. Les r\u00e9f\u00e9rences s&rsquo;arr\u00eatent l\u00e0. C&rsquo;est d\u00e9j\u00e0 pas mal. Le monde d&rsquo;UCC Dolores a sa propre structure, ses propres codes, plus proches de ceux de Ken le survivant que des mangas d\u00e9j\u00e0 cit\u00e9s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"797\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-4.jpg\" alt=\"\" class=\"wp-image-3408\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-4.jpg 600w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-4-226x300.jpg 226w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Tarquin, Tarquin &#8211; Gl\u00e9nat<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Excellente s\u00e9rie de SF, UCC Dolores est en passe de devenir une saga culte des ann\u00e9es 2020.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>UCC Dolores<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;: <\/strong>5 \u2013 Les sables de Tishala&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Space-Opera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario, Dessins &amp; Couleurs&nbsp;: <\/strong>Didier Tarquin &amp; Lyse Tarquin<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Gl\u00e9nat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 9782344055731<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>64<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 15,95 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Mad Mony \u00ab\u00a0-Impressionnant ! Tu es vraiment \u00e0 la hauteur de ta r\u00e9putation. -Joli jouet, mais il tire trop sur la droite\u2026 de trois degr\u00e9s. Je suppose que j&rsquo;ai r\u00e9ussi votre test. Je viens, mais avec mon mat\u00e9riel. -Ha ! Ha ! S&rsquo;il n&rsquo;y a que \u00e7a !&#8230; Mes chiens, je vous annonce que nous &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2023\/12\/02\/ucc-dolores-5-les-sables-de-tishala\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0UCC Dolores 5 \u2013 Les sables de Tishala\u00a0\u00ab\u00a0<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,329],"tags":[59],"class_list":["post-3405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-heroic-fantasy","tag-editions-glenat"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/12\/UCC-dolores-5-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=3405"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3405\/revisions"}],"predecessor-version":[{"id":3410,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/3405\/revisions\/3410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/3409"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=3405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=3405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=3405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}