{"id":1433,"date":"2023-04-07T00:09:31","date_gmt":"2023-04-06T22:09:31","guid":{"rendered":"http:\/\/boulevardbd.com\/?p=1433"},"modified":"2023-04-07T00:09:31","modified_gmt":"2023-04-06T22:09:31","slug":"tintin-de-a-a-z","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2023\/04\/07\/tintin-de-a-a-z\/","title":{"rendered":"Tintin de A \u00e0 Z"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color wp-block-paragraph\"><strong>Leconte est bon pour le reporter \u00e0 la houppe<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/2FAYC7rQDmdl39WWtNJdll?si=d8c4f0c98b644cd8\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color wp-element-button\" href=\"https:\/\/youtu.be\/yI3bkZuXfGI\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0Quand j&rsquo;\u00e9tais enfant, Tintin \u00e9tait comme mon grand-fr\u00e8re. Plus tard, \u00e0 l&rsquo;adolescence, je me suis consid\u00e9r\u00e9 comme son jumeau (m\u00eame si ma vie \u00e9tait nettement moins aventureuse que la sienne). Et puis, les ann\u00e9es passant, il est spontan\u00e9ment devenu mon cadet, lui qui a la chance de ne pas vieillir. Toujours est-il qu&rsquo;il ne m&rsquo;a jamais quitt\u00e9.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cin\u00e9aste connu et reconnu, Patrice Leconte n&rsquo;a jamais cach\u00e9 sa passion pour les aventures du jeune reporter \u00e0 la houppe. Leconte a d\u00e9but\u00e9 dans la bande dessin\u00e9e, avant de faire du cin\u00e9ma. Il a dessin\u00e9 dans Pilote et dans Fluide glacial. Depuis quelques ann\u00e9es, il tente de monter Les bijoux de la Castafiore en film, mais les droits sont encore en possession de Paramount. On ne sait d&rsquo;ailleurs toujours pas si Peter Jackson se lancera un jour dans le film qu&rsquo;il devait faire apr\u00e8s celui de Spielberg. Bref, refermons ici cette parenth\u00e8se cin\u00e9matographique pour revenir sur le sujet qui nous int\u00e9resse, \u00e0 savoir cet ab\u00e9c\u00e9daire sign\u00e9 Patrice Leconte.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"800\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz2.jpg\" alt=\"\" class=\"wp-image-1434\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz2.jpg 598w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz2-224x300.jpg 224w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9 &#8211; Casterman\/Moulinsart<\/strong><br><strong>\u00a9 Tintinimaginatio<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">De A comme Abdallah \u00e0 Z comme Zorrino, Leconte prouve son amour pour l&rsquo;\u0153uvre de Georges Remi. Mais attention, ou plut\u00f4t \u00ab\u00a0tant mieux\u00a0\u00bb, nous ne sommes pas ici en possession d&rsquo;un dictionnaire, mais bien d&rsquo;un ab\u00e9c\u00e9daire. Leconte ne d\u00e9finit pas chaque personnage ou chaque entr\u00e9e, car le livre n&rsquo;est pas une succession de portraits des acteurs, mais il raconte ses sentiments sur chaque sujet qu&rsquo;il traite. Leconte emploie le \u00ab\u00a0je\u00a0\u00bb \u00e0 bon escient. Ce livre est le sien. On entend sa voix. Il se d\u00e9voile \u00e0 travers cet univers si familier de tous.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"631\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz3.jpg\" alt=\"\" class=\"wp-image-1435\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz3.jpg 500w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz3-238x300.jpg 238w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9 &#8211; Casterman\/Moulinsart<\/strong><br><strong>\u00a9 Tintinimaginatio<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Dans le paragraphe \u00ab\u00a0Appartement\u00a0\u00bb, il imagine comment est le dressing de Tintin, remarquant au passage que le reporter est descendu d&rsquo;un \u00e9tage rue du Labrador. Et maintenant qu&rsquo;il loge \u00e0 Moulinsart, son appartement doit \u00eatre \u00e0 louer. Dans l&rsquo;entr\u00e9e \u00ab\u00a0Canicule\u00a0\u00bb, Leconte est boulevers\u00e9 par l&rsquo;impressionnante chaleur qui fait fondre le bitume, \u00e0 une \u00e9poque o\u00f9 l&rsquo;on ne parlait pas encore de r\u00e9chauffement climatique. L&rsquo;auteur est angoiss\u00e9 par les annonces de Philippulus le proph\u00e8te sur la fin du monde. Leconte s&rsquo;attarde longuement sur les couvertures, les comparant \u00e0 des affiches de films. Chassez le naturel, il revient au galop. Ces couvertures sont des invitations \u00e0 ouvrir les albums. Qui le fera en premier ? Patrice ou son grand-fr\u00e8re Fran\u00e7ois ? C&rsquo;est \u00e0 qui gagnera la dispute. Leconte se demande p\u00eale-m\u00eale de quoi vit Tintin ? Comment il gagne de l&rsquo;argent ? Il r\u00e9fl\u00e9chit sur sa famille et fait une analogie avec le R\u00e9mi de \u00ab\u00a0Sans famille\u00a0\u00bb par Hector Malot et le Remi de Georges Remi. Il n&rsquo;y a jamais de hasard souligne Patrice Leconte. Bien s\u00fbr, il est aussi question des personnages, on l&rsquo;a dit, et il est fort amus\u00e9 des noms \u00e9patants donn\u00e9s par Herg\u00e9 \u00e0 ses personnages, Isidore Lagop\u00e8de en t\u00eate.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"631\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz4.jpg\" alt=\"\" class=\"wp-image-1436\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz4.jpg 500w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz4-238x300.jpg 238w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Herg\u00e9 &#8211; Casterman\/Moulinsart<\/strong><br><strong>\u00a9 Tintinimaginatio<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Avec Tintin de A \u00e0 Z, Patrice Leconte fait son film des aventures de Tintin. On imagine ainsi ce qu&rsquo;il pourrait en faire sur grand \u00e9cran. En attendant de l&rsquo;y voir, on peut continuer \u00e0 lire Tintin. Quand on a fini de lire Tintin, on peut recommencer \u00e0 lire Tintin. On y trouvera toujours quelque chose de nouveau.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>One shot&nbsp;: <\/strong>Tintin de A \u00e0 Z<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Ouvrage d\u2019\u00e9tude<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Auteur : <\/strong>Patrice Leconte<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Casterman\/Moulinsart<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;: <\/strong>9782203257290<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>132<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 19,95 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leconte est bon pour le reporter \u00e0 la houppe \u00ab\u00a0Quand j&rsquo;\u00e9tais enfant, Tintin \u00e9tait comme mon grand-fr\u00e8re. Plus tard, \u00e0 l&rsquo;adolescence, je me suis consid\u00e9r\u00e9 comme son jumeau (m\u00eame si ma vie \u00e9tait nettement moins aventureuse que la sienne). Et puis, les ann\u00e9es passant, il est spontan\u00e9ment devenu mon cadet, lui qui a la chance &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2023\/04\/07\/tintin-de-a-a-z\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Tintin de A \u00e0 Z\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,93,113],"tags":[427,6,426,225,116,425,117],"class_list":["post-1433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-classique-chroniques","category-ouvrage-detude","tag-abecedaire","tag-bd","tag-dictionnaire","tag-editions-casterman","tag-herge","tag-moulinsart","tag-tintin"],"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2023\/04\/Tintin-aaz1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/1433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=1433"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/1433\/revisions"}],"predecessor-version":[{"id":1438,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/1433\/revisions\/1438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/1437"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=1433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}