{"id":12157,"date":"2026-09-02T12:00:00","date_gmt":"2026-09-02T10:00:00","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=12157"},"modified":"2026-09-01T23:32:03","modified_gmt":"2026-09-01T21:32:03","slug":"la-collection-gaston-tome-1","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2026\/09\/02\/la-collection-gaston-tome-1\/","title":{"rendered":"La collection Gaston \u2013 Tome 1"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>La naissance du gaffeur<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/3JRUwvXCn8mlU5pH1wjzkE?si=iY3q9JZtTSKHNRpJqTrqwQ\" target=\"_blank\" rel=\"noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/vku1tG24MiY\" target=\"_blank\" rel=\"noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Chers lecteurs de Spirou, on m\u2019a charg\u00e9 de vous annoncer une bonne nouvelle&nbsp;: r\u00e9pondant \u00e0 la demande de nombreux lecteurs, le journal publiera d\u00e9sormais les aventures de Gaston d\u00e8s la semaine prochaine donc ceux que la chose int\u00e9resse vibreront au r\u00e9cit des exploits admirables de notre h\u00e9ros sans emploi\u2026 C\u2019est aux crayons finement inspir\u00e9s de Jid\u00e9hem et de Franquin que nous devons cette fresque sublime&nbsp;!\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong> C\u2019est furax que Fantasio sort de son bureau. En tant qu\u2019\u00e9ditorialiste au journal de Spirou, il annonce l\u2019arriv\u00e9e d\u2019un nouveau personnage soi-disant exceptionnel. T\u2019as qu\u2019\u00e0 croire. Le nouvel employ\u00e9 va lui ficher d\u2019entr\u00e9e une pointe dans le pied en voulant ramasser les papiers. C\u2019est ballot, il a rat\u00e9 la boulette\u2026 et en a commis une. Au fil des semaines, Gaston va sans cesse faire p\u00e9ter des c\u00e2bles \u00e0 son patron. Il vaut mieux \u00eatre seul que mal accompagn\u00e9, mais c\u2019est trop tard. Va falloir faire avec&nbsp;! Entre exp\u00e9riences, gaffes et travail\u2026 non, pas travail\u2026, Gaston squatte les locaux de la r\u00e9daction au grand dam de ses coll\u00e8gues de bureaux. Ce premier recueil chronologique se termine par une s\u00e9rie de gags publicitaires au profit de la limonade belge Piedb\u0153uf pr\u00e9sent\u00e9s sous leur forme originale.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0001-1-722x1024.jpg\" alt=\"\" class=\"wp-image-12159\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0001-1-722x1024.jpg 722w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0001-1-212x300.jpg 212w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0001-1.jpg 768w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Franquin, Jid\u00e9hem \u2013 Hachette\/Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9sentons quand m\u00eame Gaston pour donner une envie de lecture aux novices de la s\u00e9rie. Gaston Lagaffe est un gar\u00e7on \u00e0 tout faire qui travaille dans l\u2019immeuble des \u00e9ditions Dupuis \u00e9ditant entre autres le beau journal de Spirou. Inventeur inv\u00e9t\u00e9r\u00e9 et gaffeur patent\u00e9, il est un boulet attachant pour tous ses coll\u00e8gues de travail, avec en premier lieu Fantasio, son sup\u00e9rieur hi\u00e9rarchique, que Gaston fait constamment sortir de ses gonds et qui sera ensuite remplac\u00e9 par Prunelle lorsque Franquin abandonnera Spirou, mais \u00e7a on le verra bien plus tard. Au fil des albums, appara\u00eetront sa coll\u00e8gue Mam\u2019zelle Jeanne, transie d\u2019amour pour lui, Monsieur de Mesmaeker et ses \u00e9ternels contrats qu\u2019il ne r\u00e9ussira jamais \u00e0 faire signer, et, pour ne citer que les plus c\u00e9l\u00e8bres l\u2019agent Longtarin et son carnet de contredanses.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0002-727x1024.jpg\" alt=\"\" class=\"wp-image-12160\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0002-727x1024.jpg 727w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0002-213x300.jpg 213w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0002.jpg 768w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Franquin, Jid\u00e9hem \u2013 Hachette\/Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">2,50 \u20ac pour ce tome 1, qui dit mieux&nbsp;? Dans un cahier compl\u00e9mentaire de 16 pages, on revient sur la num\u00e9rotation des albums au fil des diff\u00e9rentes \u00e9ditions, des mythiques demi-albums \u00e0 la collection actuelle. La vie et l\u2019\u0153uvre de Franquin sont racont\u00e9s dans Les premiers pas d\u2019un dessinateur. Avant un portfolio final, on nous explique comment un personnage sans emploi d\u00e9barquant \u00e0 l\u2019improviste dans les pages d\u2019animation du journal de Spirou est devenu un (anti-)h\u00e9ros de bande dessin\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis fin juillet, Hachette collection a lanc\u00e9 cette \u00e9dition luxueuse grand format \u00e0 dos toil\u00e9. Les lecteurs pourront acheter les albums chez leur marchand de journaux, mais les abonn\u00e9s b\u00e9n\u00e9ficient de cadeaux consid\u00e9rables (tir\u00e9s \u00e0 part, album Bravo les brothers, recueils de Monstres et t-shirt). Un nouveau volume avec un dossier exclusif para\u00eetra tous les quinze jours, jusqu\u2019\u00e0 la reprise fort honorable de Delac, avant de terminer par la s\u00e9rie Modeste et Pompon.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1024\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0003-750x1024.jpg\" alt=\"\" class=\"wp-image-12161\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0003-750x1024.jpg 750w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0003-220x300.jpg 220w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/20260901142724187_0003.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 Franquin, Jid\u00e9hem \u2013 Hachette\/Dupuis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Pour un chroniqueur BD, faire un papier sur Franquin, c\u2019est comme si un fid\u00e8le \u00e9crivait sur Dieu. Cette collection est une madeleine de Proust pour les uns et la meilleure fa\u00e7on de d\u00e9couvrir Lagaffe pour les autres\u2026s\u2019il en reste encore. Si de nouveaux lecteurs d\u00e9couvrent Gaston gr\u00e2ce \u00e0 ces r\u00e9\u00e9ditions, Hachette et Dupuis auront r\u00e9ussi leur pari.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie :<\/strong> La collection Gaston<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;:<\/strong> Tome 1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Humour<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dessins&nbsp;&amp; Sc\u00e9nario&nbsp;:<\/strong> Franquin, avec la participation de Jid\u00e9hem<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Hachette\/Dupuis&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages :<\/strong> 64<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 2,50 \u20ac<strong>\u00a0<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>La naissance du gaffeur \u00ab\u00a0-Chers lecteurs de Spirou, on m\u2019a charg\u00e9 de vous annoncer une bonne nouvelle&nbsp;: r\u00e9pondant \u00e0 la demande de nombreux lecteurs, le journal publiera d\u00e9sormais les aventures de Gaston d\u00e8s la semaine prochaine donc ceux que la chose int\u00e9resse vibreront au r\u00e9cit des exploits admirables de notre h\u00e9ros sans emploi\u2026 C\u2019est aux &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2026\/09\/02\/la-collection-gaston-tome-1\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0La collection Gaston \u2013 Tome 1\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":12162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,93,19],"tags":[7,953],"class_list":["post-12157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-classique-chroniques","category-humour","tag-editions-dupuis","tag-editions-hachette"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/09\/Couv_541710.jpg","_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/12157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=12157"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/12157\/revisions"}],"predecessor-version":[{"id":12163,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/12157\/revisions\/12163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/12162"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=12157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=12157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=12157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}