{"id":10682,"date":"2026-02-10T17:00:00","date_gmt":"2026-02-10T16:00:00","guid":{"rendered":"https:\/\/boulevardbd.com\/?p=10682"},"modified":"2026-01-29T23:11:38","modified_gmt":"2026-01-29T22:11:38","slug":"popeye-2-sundays-1933-1938","status":"publish","type":"post","link":"https:\/\/boulevardbd.com\/index.php\/2026\/02\/10\/popeye-2-sundays-1933-1938\/","title":{"rendered":"Popeye \u2013 2 &#8211; Sundays 1933-1938"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><strong>Les muscles de la famille<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/open.spotify.com\/episode\/18NJ3MnamWg1kxEzBRlzgF?si=za3rs7c_TG2FrOnrHn7dcQ\" target=\"_blank\" rel=\"noreferrer noopener\">Ecouter<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-luminous-vivid-amber-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/youtu.be\/7DKw3eVHoIc\" target=\"_blank\" rel=\"noreferrer noopener\">Regarder<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00ab\u00a0-Popeye, j\u2019viens t\u2019causer d\u2019un truc. Si on r\u2019p\u00e8re l\u2019\u00eele au magot, y\u2019a moyen d\u2019se marrer un bon coup&nbsp;! Y\u2019aura du grabuge et d\u2019l\u2019aventure, c\u2019est s\u00fbr&nbsp;! Y s\u2019peut qu\u2019on y laisse not\u2019peau, ou qu\u2019on r\u2019vienne les poches pleines d\u2019or. L\u2019or des pirates&nbsp;! Des rubis et des perles grosses comme des \u0153ufs.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>-J\u2019en ai ma claque de c\u2019boui-boui. J\u2019sens la mer qui m\u2019arpelle, et j\u2019aime le danger&nbsp;! Allez, on l\u00e8ve l\u2019ancre.\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Olive est affol\u00e9e. Popeye, son amoureux, est en train de se battre en plein milieu du restaurant. Elle envoie Wimpy chercher la police avant qu\u2019ils s\u2019entretuent. Peine perdue, le marin s\u2019amusait avec son vieux pote Bill Barnacle, alias Salty, frangin de l\u2019ancien club des gens d\u2019mer qu\u2019il n\u2019avait pas vu depuis vingt ans. Le loup de mer est venu causer d\u2019un truc \u00e0 Popeye&nbsp;: l\u2019\u00eele au magot. S\u2019ils la retrouvent, y\u2019a moyen de revenir les poches pleines d\u2019or et de se marrer un bon coup avec du grabuge et de l\u2019aventure. Mais ils peuvent aussi y laisser leur peau. Il n\u2019en fallait pas plus pour que Popeye ressente l\u2019appel de la mer. L\u2019or des pirates n\u2019attend que lui. Allez, il est temps de lever l\u2019ancre, comme \u00e0 la belle \u00e9poque o\u00f9 les bateaux \u00e9taient en bois et les hommes en fer.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"768\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-2-Moyen.jpg\" alt=\"\" class=\"wp-image-10683\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-2-Moyen.jpg 906w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-2-Moyen-300x254.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-2-Moyen-768x651.jpg 768w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2025, King Features Syndicate<\/strong><br><strong>\u00a9 Futuropolis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cette seconde salve des planches dominicales de Popeye sign\u00e9es de son cr\u00e9ateur Elzie Crisler Segar commence par une grande aventure de 32 planches. Humour, myst\u00e8re, monstre et action sont au g\u00e9n\u00e9rique de ce p\u00e9riple dans lequel Olive et Wimpy vont accompagner le marin \u00e0 la pipe, dans un vrai voyage sur l\u2019oc\u00e9an, une fois n\u2019est pas coutume. Que va faire Popeye de la fortune qu\u2019il va ramener&nbsp;? Vous le d\u00e9couvrirez par la suite. Tout ce qu\u2019on peut dire, c\u2019est qu\u2019il lui faudra trouver une nouvelle source de revenus. Premi\u00e8re \u00e9tape, d\u00e9fier Kid Nitro sur le ring. Le cogneur le plus f\u00e9roce de toute l\u2019Am\u00e9rique va-t-il r\u00e9duire notre muscl\u00e9 des avant-bras en bouillie&nbsp;?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"768\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-3-Moyen.jpg\" alt=\"\" class=\"wp-image-10684\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-3-Moyen.jpg 912w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-3-Moyen-300x253.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-3-Moyen-768x647.jpg 768w\" sizes=\"auto, (max-width: 912px) 100vw, 912px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2025, King Features Syndicate<\/strong><br><strong>\u00a9 Futuropolis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Apparu dans les strips quotidiens en juillet 1933, Mimosa, le b\u00e9b\u00e9 abandonn\u00e9 \u00e0 Popeye, ne d\u00e9barque dans les planches dominicales qu\u2019en octobre 1934. Popeye l\u2019avait confi\u00e9 \u00e0 une dame, mais le nourrisson lui manque. Popeye l\u2019embarque. On le retrouve \u00e9pisodiquement et il l\u2019accompagne dans une ru\u00e9e vers l\u2019or. Arriv\u00e9e d\u2019un autre personnage mythique quatre mois apr\u00e8s son apparition dans les strips. En ao\u00fbt 1936, le public dominical d\u00e9couvre Eug\u00e8ne le Jeep, un animal qui a travers\u00e9 la barri\u00e8re dimensionnelle. Il peut pr\u00e9dire l\u2019avenir, r\u00e9pondre par oui ou non et dit toujours la v\u00e9rit\u00e9. C\u2019est l\u2019oncle d\u2019Olive qui lui a envoy\u00e9 d\u2019Afrique. La bestiole jaune sera source d\u2019inspiration de Franquin pour le Marsupilami. Le 2 octobre 1938, Segar publie sa derni\u00e8re planche hebdomadaire avant de d\u00e9c\u00e9der quelques jours plus tard d\u2019une leuc\u00e9mie, \u00e0 seulement 44 ans. On y retrouve Olive en col\u00e8re contre le p\u00f4pa de Popeye, qui aime bien se d\u00e9guiser en son fils pour lui faire la cour.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"878\" height=\"768\" src=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-4-Moyen.jpg\" alt=\"\" class=\"wp-image-10685\" srcset=\"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-4-Moyen.jpg 878w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-4-Moyen-300x262.jpg 300w, https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-4-Moyen-768x672.jpg 768w\" sizes=\"auto, (max-width: 878px) 100vw, 878px\" \/><figcaption class=\"wp-element-caption\"><strong>\u00a9 2025, King Features Syndicate<\/strong><br><strong>\u00a9 Futuropolis<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En deux volumes, les \u00e9ditions Futuropolis ont r\u00e9alis\u00e9 un travail patrimonial d\u2019exception en publiant l\u2019int\u00e9gralit\u00e9 des planches du dimanche de Popeye the sailor man sign\u00e9es par le cr\u00e9ateur du personnage. Esp\u00e9rons que le voyage se poursuive avec les pages de ses successeurs.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Popeye chauffeur de taxi - Dessin anim\u00e9\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/6fJdNq5W8kw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9rie : <\/strong>Popeye<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tome&nbsp;:<\/strong> 2 &#8211; Sundays 1933-1938<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Genre&nbsp;:<\/strong> Humour<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sc\u00e9nario &amp; Dessins&nbsp;: <\/strong>Elzie Crisler Segar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traduction : <\/strong>Sidonie Van Den Dries<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9diteur :<\/strong> Futuropolis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ISBN&nbsp;:<\/strong> 9782754848787<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombre de pages : <\/strong>256<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix :<\/strong> 34 \u20ac<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Les muscles de la famille \u00ab\u00a0-Popeye, j\u2019viens t\u2019causer d\u2019un truc. Si on r\u2019p\u00e8re l\u2019\u00eele au magot, y\u2019a moyen d\u2019se marrer un bon coup&nbsp;! Y\u2019aura du grabuge et d\u2019l\u2019aventure, c\u2019est s\u00fbr&nbsp;! Y s\u2019peut qu\u2019on y laisse not\u2019peau, ou qu\u2019on r\u2019vienne les poches pleines d\u2019or. L\u2019or des pirates&nbsp;! Des rubis et des perles grosses comme des \u0153ufs. &#8230; <a href=\"https:\/\/boulevardbd.com\/index.php\/2026\/02\/10\/popeye-2-sundays-1933-1938\/\" class=\"more-link\">Lire plus<span class=\"screen-reader-text\"> \u00ab\u00a0Popeye \u2013 2 &#8211; Sundays 1933-1938\u00a0\u00bb<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":10686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16,93,19,437],"tags":[466],"class_list":["post-10682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-classique-chroniques","category-humour","category-peripeties","tag-editions-futuropolis"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/boulevardbd.com\/wp-content\/uploads\/2026\/01\/Popeye-Sundays-33-38-1-Moyen.jpg","_links":{"self":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/10682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/comments?post=10682"}],"version-history":[{"count":1,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/10682\/revisions"}],"predecessor-version":[{"id":10687,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/posts\/10682\/revisions\/10687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media\/10686"}],"wp:attachment":[{"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/media?parent=10682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/categories?post=10682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boulevardbd.com\/index.php\/wp-json\/wp\/v2\/tags?post=10682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}